{"id":8998,"date":"2021-10-29T10:10:55","date_gmt":"2021-10-29T14:10:55","guid":{"rendered":"https:\/\/bumped.org\/idola\/?page_id=8998"},"modified":"2021-10-29T10:10:55","modified_gmt":"2021-10-29T14:10:55","slug":"character-odette-ex","status":"publish","type":"page","link":"https:\/\/bumped.org\/idola\/idola-character-database\/character-odette-ex\/","title":{"rendered":"Character: Odette [EX]"},"content":{"rendered":"<p><a href=\"https:\/\/bumped.org\/idola\/idola-character-database\/\">&lt; Back to Characters<\/a><\/p>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_11.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-9003\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_11.png?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_11.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_11.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_11.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_11.png?resize=60%2C60&amp;ssl=1 60w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_11.png?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_02.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-9004\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_02.png?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_02.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_02.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_02.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_02.png?resize=60%2C60&amp;ssl=1 60w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_02.png?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_12.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-9002\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_12.png?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_12.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_12.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_12.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_12.png?resize=60%2C60&amp;ssl=1 60w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/10\/ch_whole191065_12.png?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 33.3333%; text-align: center;\">\n<p>Odette [EX] (Law)<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-weak-hit-damage.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5886\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-weak-hit-damage.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Weak Hit Type<\/p>\n<\/th>\n<th style=\"width: 33.3333%; text-align: center;\">Odette [EX]<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-attack.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-5889 alignnone\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-attack.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Attack Type<\/th>\n<th style=\"width: 33.3333%; text-align: center;\">Odette [EX] (Chaos)<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/type-critical-hit-rate.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-5884 alignnone\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/type-critical-hit-rate.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Critical Hit Type<\/th>\n<\/tr>\n<\/tbody>\n<\/table>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 100%; border-color: #757575;\" border=\"1\" width=\"100%\">\n<thead>\n<tr>\n<td style=\"background-color: #e3e3e3; width: 20%; border-color: grey; text-align: center; vertical-align: middle;\" width=\"20%\">Rarity<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\" width=\"30%\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; width: 20%; text-align: center; vertical-align: middle;\" width=\"20%\">Faction<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\" width=\"30%\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1280\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Chaos-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Chaos<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"border-color: #757575;\">\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Class<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">Shooter<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Element<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1070\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/element-icon-fire-e1543536690353.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/>\u00a0Fire<\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Idola<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1079\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/idola-icon-7-e1543537574755.png?resize=17%2C22&#038;ssl=1\" alt=\"\" width=\"17\" height=\"22\" \/> Hydra<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Fates<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1281\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Law-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Law<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1280\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Chaos-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Chaos<\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Date<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">2021\/10\/26<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Race<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">Demonic<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"sexyblue\" style=\"text-align: center;\">\nCharacter Stats<\/h2>\n<ul id=\"DBLimits\" class=\"nav nav-tabs\" role=\"tablist\">\n<li class=\"nav-item\"><a id=\"limi0-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD0\" data-toggle=\"tab\">Default<\/a><\/li>\n<li class=\"nav-item\"><a id=\"limi1-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD1\" data-toggle=\"tab\">Law<\/a><\/li>\n<li class=\"nav-item\"><a id=\"limi2-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD2\" data-toggle=\"tab\">Chaos<\/a><\/li>\n<\/ul>\n<div id=\"DBStats\" class=\"tab-content small\">\n<div id=\"FD0\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD0-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-0\"><li class=\"active\"><a class=\"\" href=\"#pane-0-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-0-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22089<br \/>\n(25089)<\/td>\n<td style=\"width: 20%; text-align: center;\">689<br \/>\n(749)<\/td>\n<td style=\"width: 20%; text-align: center;\">592<br \/>\n(602)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">631<br \/>\n(631)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22899<br \/>\n(25899)<\/td>\n<td style=\"width: 20%; text-align: center;\">705<br \/>\n(765)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(614)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">647<br \/>\n(647)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23709<br \/>\n(26709)<\/td>\n<td style=\"width: 20%; text-align: center;\">721<br \/>\n(781)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">663<br \/>\n(663)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24714<br \/>\n(27714)<\/td>\n<td style=\"width: 20%; text-align: center;\">741<br \/>\n(801)<\/td>\n<td style=\"width: 20%; text-align: center;\">631<br \/>\n(641)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">683<br \/>\n(683)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26139<br \/>\n(29139)<\/td>\n<td style=\"width: 20%; text-align: center;\">771<br \/>\n(831)<\/td>\n<td style=\"width: 20%; text-align: center;\">652<br \/>\n(662)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">713<br \/>\n(713)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22609<br \/>\n(25609)<\/td>\n<td style=\"width: 20%; text-align: center;\">698<br \/>\n(758)<\/td>\n<td style=\"width: 20%; text-align: center;\">599<br \/>\n(609)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">642<br \/>\n(642)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23419<br \/>\n(26419)<\/td>\n<td style=\"width: 20%; text-align: center;\">714<br \/>\n(774)<\/td>\n<td style=\"width: 20%; text-align: center;\">611<br \/>\n(621)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">658<br \/>\n(658)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24229<br \/>\n(27229)<\/td>\n<td style=\"width: 20%; text-align: center;\">730<br \/>\n(790)<\/td>\n<td style=\"width: 20%; text-align: center;\">623<br \/>\n(633)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">674<br \/>\n(674)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25234<br \/>\n(28234)<\/td>\n<td style=\"width: 20%; text-align: center;\">750<br \/>\n(810)<\/td>\n<td style=\"width: 20%; text-align: center;\">638<br \/>\n(648)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">694<br \/>\n(694)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26659<br \/>\n(29659)<\/td>\n<td style=\"width: 20%; text-align: center;\">780<br \/>\n(840)<\/td>\n<td style=\"width: 20%; text-align: center;\">659<br \/>\n(669)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">724<br \/>\n(724)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22764<br \/>\n(25764)<\/td>\n<td style=\"width: 20%; text-align: center;\">699<br \/>\n(759)<\/td>\n<td style=\"width: 20%; text-align: center;\">600<br \/>\n(610)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">645<br \/>\n(645)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23574<br \/>\n(26574)<\/td>\n<td style=\"width: 20%; text-align: center;\">715<br \/>\n(775)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(622)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">661<br \/>\n(661)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24384<br \/>\n(27384)<\/td>\n<td style=\"width: 20%; text-align: center;\">731<br \/>\n(791)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(634)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">677<br \/>\n(677)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25389<br \/>\n(28389)<\/td>\n<td style=\"width: 20%; text-align: center;\">751<br \/>\n(811)<\/td>\n<td style=\"width: 20%; text-align: center;\">639<br \/>\n(649)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">697<br \/>\n(697)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26814<br \/>\n(29814)<\/td>\n<td style=\"width: 20%; text-align: center;\">781<br \/>\n(841)<\/td>\n<td style=\"width: 20%; text-align: center;\">660<br \/>\n(670)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">727<br \/>\n(727)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22944<br \/>\n(25944)<\/td>\n<td style=\"width: 20%; text-align: center;\">701<br \/>\n(761)<\/td>\n<td style=\"width: 20%; text-align: center;\">601<br \/>\n(611)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">649<br \/>\n(649)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23754<br \/>\n(26754)<\/td>\n<td style=\"width: 20%; text-align: center;\">717<br \/>\n(777)<\/td>\n<td style=\"width: 20%; text-align: center;\">613<br \/>\n(623)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">665<br \/>\n(665)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24564<br \/>\n(27564)<\/td>\n<td style=\"width: 20%; text-align: center;\">733<br \/>\n(793)<\/td>\n<td style=\"width: 20%; text-align: center;\">625<br \/>\n(635)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">681<br \/>\n(681)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25569<br \/>\n(28569)<\/td>\n<td style=\"width: 20%; text-align: center;\">753<br \/>\n(813)<\/td>\n<td style=\"width: 20%; text-align: center;\">640<br \/>\n(650)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">701<br \/>\n(701)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26994<br \/>\n(29994)<\/td>\n<td style=\"width: 20%; text-align: center;\">783<br \/>\n(843)<\/td>\n<td style=\"width: 20%; text-align: center;\">661<br \/>\n(671)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">731<br \/>\n(731)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23134<br \/>\n(26134)<\/td>\n<td style=\"width: 20%; text-align: center;\">703<br \/>\n(763)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(612)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">653<br \/>\n(653)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23944<br \/>\n(26944)<\/td>\n<td style=\"width: 20%; text-align: center;\">719<br \/>\n(779)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">669<br \/>\n(669)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24754<br \/>\n(27754)<\/td>\n<td style=\"width: 20%; text-align: center;\">735<br \/>\n(795)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(636)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">685<br \/>\n(685)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25759<br \/>\n(28759)<\/td>\n<td style=\"width: 20%; text-align: center;\">755<br \/>\n(815)<\/td>\n<td style=\"width: 20%; text-align: center;\">641<br \/>\n(651)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">705<br \/>\n(705)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27184<br \/>\n(30184)<\/td>\n<td style=\"width: 20%; text-align: center;\">785<br \/>\n(845)<\/td>\n<td style=\"width: 20%; text-align: center;\">662<br \/>\n(672)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">735<br \/>\n(735)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23339<br \/>\n(26339)<\/td>\n<td style=\"width: 20%; text-align: center;\">705<br \/>\n(765)<\/td>\n<td style=\"width: 20%; text-align: center;\">603<br \/>\n(613)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">657<br \/>\n(657)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24149<br \/>\n(27149)<\/td>\n<td style=\"width: 20%; text-align: center;\">721<br \/>\n(781)<\/td>\n<td style=\"width: 20%; text-align: center;\">615<br \/>\n(625)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">673<br \/>\n(673)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24959<br \/>\n(27959)<\/td>\n<td style=\"width: 20%; text-align: center;\">737<br \/>\n(797)<\/td>\n<td style=\"width: 20%; text-align: center;\">627<br \/>\n(637)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">689<br \/>\n(689)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25964<br \/>\n(28964)<\/td>\n<td style=\"width: 20%; text-align: center;\">757<br \/>\n(817)<\/td>\n<td style=\"width: 20%; text-align: center;\">642<br \/>\n(652)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">709<br \/>\n(709)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27389<br \/>\n(30389)<\/td>\n<td style=\"width: 20%; text-align: center;\">787<br \/>\n(847)<\/td>\n<td style=\"width: 20%; text-align: center;\">663<br \/>\n(673)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">739<br \/>\n(739)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23564<br \/>\n(26564)<\/td>\n<td style=\"width: 20%; text-align: center;\">707<br \/>\n(767)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(614)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">662<br \/>\n(662)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24374<br \/>\n(27374)<\/td>\n<td style=\"width: 20%; text-align: center;\">723<br \/>\n(783)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">678<br \/>\n(678)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25184<br \/>\n(28184)<\/td>\n<td style=\"width: 20%; text-align: center;\">739<br \/>\n(799)<\/td>\n<td style=\"width: 20%; text-align: center;\">628<br \/>\n(638)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">694<br \/>\n(694)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26189<br \/>\n(29189)<\/td>\n<td style=\"width: 20%; text-align: center;\">759<br \/>\n(819)<\/td>\n<td style=\"width: 20%; text-align: center;\">643<br \/>\n(653)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">714<br \/>\n(714)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27614<br \/>\n(30614)<\/td>\n<td style=\"width: 20%; text-align: center;\">789<br \/>\n(849)<\/td>\n<td style=\"width: 20%; text-align: center;\">664<br \/>\n(674)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">744<br \/>\n(744)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23799<br \/>\n(26799)<\/td>\n<td style=\"width: 20%; text-align: center;\">709<br \/>\n(769)<\/td>\n<td style=\"width: 20%; text-align: center;\">605<br \/>\n(615)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">667<br \/>\n(667)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24609<br \/>\n(27609)<\/td>\n<td style=\"width: 20%; text-align: center;\">725<br \/>\n(785)<\/td>\n<td style=\"width: 20%; text-align: center;\">617<br \/>\n(627)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">683<br \/>\n(683)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25419<br \/>\n(28419)<\/td>\n<td style=\"width: 20%; text-align: center;\">741<br \/>\n(801)<\/td>\n<td style=\"width: 20%; text-align: center;\">629<br \/>\n(639)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">699<br \/>\n(699)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26424<br \/>\n(29424)<\/td>\n<td style=\"width: 20%; text-align: center;\">761<br \/>\n(821)<\/td>\n<td style=\"width: 20%; text-align: center;\">644<br \/>\n(654)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">719<br \/>\n(719)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27849<br \/>\n(30849)<\/td>\n<td style=\"width: 20%; text-align: center;\">791<br \/>\n(851)<\/td>\n<td style=\"width: 20%; text-align: center;\">665<br \/>\n(675)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">749<br \/>\n(749)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24049<br \/>\n(27049)<\/td>\n<td style=\"width: 20%; text-align: center;\">712<br \/>\n(772)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(616)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">672<br \/>\n(672)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24859<br \/>\n(27859)<\/td>\n<td style=\"width: 20%; text-align: center;\">728<br \/>\n(788)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(628)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">688<br \/>\n(688)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25669<br \/>\n(28669)<\/td>\n<td style=\"width: 20%; text-align: center;\">744<br \/>\n(804)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(640)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">704<br \/>\n(704)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26674<br \/>\n(29674)<\/td>\n<td style=\"width: 20%; text-align: center;\">764<br \/>\n(824)<\/td>\n<td style=\"width: 20%; text-align: center;\">645<br \/>\n(655)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">724<br \/>\n(724)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28099<br \/>\n(31099)<\/td>\n<td style=\"width: 20%; text-align: center;\">794<br \/>\n(854)<\/td>\n<td style=\"width: 20%; text-align: center;\">666<br \/>\n(676)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">754<br \/>\n(754)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24319<br \/>\n(27319)<\/td>\n<td style=\"width: 20%; text-align: center;\">715<br \/>\n(775)<\/td>\n<td style=\"width: 20%; text-align: center;\">608<br \/>\n(618)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">677<br \/>\n(677)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25129<br \/>\n(28129)<\/td>\n<td style=\"width: 20%; text-align: center;\">731<br \/>\n(791)<\/td>\n<td style=\"width: 20%; text-align: center;\">620<br \/>\n(630)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">693<br \/>\n(693)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25939<br \/>\n(28939)<\/td>\n<td style=\"width: 20%; text-align: center;\">747<br \/>\n(807)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(642)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">709<br \/>\n(709)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26944<br \/>\n(29944)<\/td>\n<td style=\"width: 20%; text-align: center;\">767<br \/>\n(827)<\/td>\n<td style=\"width: 20%; text-align: center;\">647<br \/>\n(657)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">729<br \/>\n(729)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28369<br \/>\n(31369)<\/td>\n<td style=\"width: 20%; text-align: center;\">797<br \/>\n(857)<\/td>\n<td style=\"width: 20%; text-align: center;\">668<br \/>\n(678)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">759<br \/>\n(759)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<div id=\"FD1\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD1-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-1\"><li class=\"active\"><a class=\"\" href=\"#pane-1-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-1-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21889<br \/>\n(24889)<\/td>\n<td style=\"width: 20%; text-align: center;\">649<br \/>\n(669)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(612)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">641<br \/>\n(661)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22699<br \/>\n(25699)<\/td>\n<td style=\"width: 20%; text-align: center;\">665<br \/>\n(685)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">657<br \/>\n(677)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23509<br \/>\n(26509)<\/td>\n<td style=\"width: 20%; text-align: center;\">681<br \/>\n(701)<\/td>\n<td style=\"width: 20%; text-align: center;\">636<br \/>\n(636)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">673<br \/>\n(693)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24514<br \/>\n(27514)<\/td>\n<td style=\"width: 20%; text-align: center;\">701<br \/>\n(721)<\/td>\n<td style=\"width: 20%; text-align: center;\">651<br \/>\n(651)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">693<br \/>\n(713)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25939<br \/>\n(28939)<\/td>\n<td style=\"width: 20%; text-align: center;\">731<br \/>\n(751)<\/td>\n<td style=\"width: 20%; text-align: center;\">672<br \/>\n(672)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">723<br \/>\n(743)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22409<br \/>\n(25409)<\/td>\n<td style=\"width: 20%; text-align: center;\">658<br \/>\n(678)<\/td>\n<td style=\"width: 20%; text-align: center;\">619<br \/>\n(619)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">652<br \/>\n(672)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23219<br \/>\n(26219)<\/td>\n<td style=\"width: 20%; text-align: center;\">674<br \/>\n(694)<\/td>\n<td style=\"width: 20%; text-align: center;\">631<br \/>\n(631)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">668<br \/>\n(688)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24029<br \/>\n(27029)<\/td>\n<td style=\"width: 20%; text-align: center;\">690<br \/>\n(710)<\/td>\n<td style=\"width: 20%; text-align: center;\">643<br \/>\n(643)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">684<br \/>\n(704)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25034<br \/>\n(28034)<\/td>\n<td style=\"width: 20%; text-align: center;\">710<br \/>\n(730)<\/td>\n<td style=\"width: 20%; text-align: center;\">658<br \/>\n(658)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">704<br \/>\n(724)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26459<br \/>\n(29459)<\/td>\n<td style=\"width: 20%; text-align: center;\">740<br \/>\n(760)<\/td>\n<td style=\"width: 20%; text-align: center;\">679<br \/>\n(679)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">734<br \/>\n(754)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22564<br \/>\n(25564)<\/td>\n<td style=\"width: 20%; text-align: center;\">659<br \/>\n(679)<\/td>\n<td style=\"width: 20%; text-align: center;\">620<br \/>\n(620)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">655<br \/>\n(675)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23374<br \/>\n(26374)<\/td>\n<td style=\"width: 20%; text-align: center;\">675<br \/>\n(695)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(632)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">671<br \/>\n(691)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24184<br \/>\n(27184)<\/td>\n<td style=\"width: 20%; text-align: center;\">691<br \/>\n(711)<\/td>\n<td style=\"width: 20%; text-align: center;\">644<br \/>\n(644)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">687<br \/>\n(707)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25189<br \/>\n(28189)<\/td>\n<td style=\"width: 20%; text-align: center;\">711<br \/>\n(731)<\/td>\n<td style=\"width: 20%; text-align: center;\">659<br \/>\n(659)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">707<br \/>\n(727)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26614<br \/>\n(29614)<\/td>\n<td style=\"width: 20%; text-align: center;\">741<br \/>\n(761)<\/td>\n<td style=\"width: 20%; text-align: center;\">680<br \/>\n(680)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">737<br \/>\n(757)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22744<br \/>\n(25744)<\/td>\n<td style=\"width: 20%; text-align: center;\">661<br \/>\n(681)<\/td>\n<td style=\"width: 20%; text-align: center;\">621<br \/>\n(621)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">659<br \/>\n(679)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23554<br \/>\n(26554)<\/td>\n<td style=\"width: 20%; text-align: center;\">677<br \/>\n(697)<\/td>\n<td style=\"width: 20%; text-align: center;\">633<br \/>\n(633)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">675<br \/>\n(695)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24364<br \/>\n(27364)<\/td>\n<td style=\"width: 20%; text-align: center;\">693<br \/>\n(713)<\/td>\n<td style=\"width: 20%; text-align: center;\">645<br \/>\n(645)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">691<br \/>\n(711)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25369<br \/>\n(28369)<\/td>\n<td style=\"width: 20%; text-align: center;\">713<br \/>\n(733)<\/td>\n<td style=\"width: 20%; text-align: center;\">660<br \/>\n(660)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">711<br \/>\n(731)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26794<br \/>\n(29794)<\/td>\n<td style=\"width: 20%; text-align: center;\">743<br \/>\n(763)<\/td>\n<td style=\"width: 20%; text-align: center;\">681<br \/>\n(681)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">741<br \/>\n(761)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22934<br \/>\n(25934)<\/td>\n<td style=\"width: 20%; text-align: center;\">663<br \/>\n(683)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(622)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">663<br \/>\n(683)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23744<br \/>\n(26744)<\/td>\n<td style=\"width: 20%; text-align: center;\">679<br \/>\n(699)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(634)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">679<br \/>\n(699)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24554<br \/>\n(27554)<\/td>\n<td style=\"width: 20%; text-align: center;\">695<br \/>\n(715)<\/td>\n<td style=\"width: 20%; text-align: center;\">646<br \/>\n(646)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">695<br \/>\n(715)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25559<br \/>\n(28559)<\/td>\n<td style=\"width: 20%; text-align: center;\">715<br \/>\n(735)<\/td>\n<td style=\"width: 20%; text-align: center;\">661<br \/>\n(661)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">715<br \/>\n(735)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26984<br \/>\n(29984)<\/td>\n<td style=\"width: 20%; text-align: center;\">745<br \/>\n(765)<\/td>\n<td style=\"width: 20%; text-align: center;\">682<br \/>\n(682)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">745<br \/>\n(765)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23139<br \/>\n(26139)<\/td>\n<td style=\"width: 20%; text-align: center;\">665<br \/>\n(685)<\/td>\n<td style=\"width: 20%; text-align: center;\">623<br \/>\n(623)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">667<br \/>\n(687)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23949<br \/>\n(26949)<\/td>\n<td style=\"width: 20%; text-align: center;\">681<br \/>\n(701)<\/td>\n<td style=\"width: 20%; text-align: center;\">635<br \/>\n(635)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">683<br \/>\n(703)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24759<br \/>\n(27759)<\/td>\n<td style=\"width: 20%; text-align: center;\">697<br \/>\n(717)<\/td>\n<td style=\"width: 20%; text-align: center;\">647<br \/>\n(647)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">699<br \/>\n(719)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25764<br \/>\n(28764)<\/td>\n<td style=\"width: 20%; text-align: center;\">717<br \/>\n(737)<\/td>\n<td style=\"width: 20%; text-align: center;\">662<br \/>\n(662)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">719<br \/>\n(739)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27189<br \/>\n(30189)<\/td>\n<td style=\"width: 20%; text-align: center;\">747<br \/>\n(767)<\/td>\n<td style=\"width: 20%; text-align: center;\">683<br \/>\n(683)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">749<br \/>\n(769)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23364<br \/>\n(26364)<\/td>\n<td style=\"width: 20%; text-align: center;\">667<br \/>\n(687)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">672<br \/>\n(692)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24174<br \/>\n(27174)<\/td>\n<td style=\"width: 20%; text-align: center;\">683<br \/>\n(703)<\/td>\n<td style=\"width: 20%; text-align: center;\">636<br \/>\n(636)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">688<br \/>\n(708)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24984<br \/>\n(27984)<\/td>\n<td style=\"width: 20%; text-align: center;\">699<br \/>\n(719)<\/td>\n<td style=\"width: 20%; text-align: center;\">648<br \/>\n(648)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">704<br \/>\n(724)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25989<br \/>\n(28989)<\/td>\n<td style=\"width: 20%; text-align: center;\">719<br \/>\n(739)<\/td>\n<td style=\"width: 20%; text-align: center;\">663<br \/>\n(663)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">724<br \/>\n(744)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27414<br \/>\n(30414)<\/td>\n<td style=\"width: 20%; text-align: center;\">749<br \/>\n(769)<\/td>\n<td style=\"width: 20%; text-align: center;\">684<br \/>\n(684)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">754<br \/>\n(774)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23599<br \/>\n(26599)<\/td>\n<td style=\"width: 20%; text-align: center;\">669<br \/>\n(689)<\/td>\n<td style=\"width: 20%; text-align: center;\">625<br \/>\n(625)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">677<br \/>\n(697)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24409<br \/>\n(27409)<\/td>\n<td style=\"width: 20%; text-align: center;\">685<br \/>\n(705)<\/td>\n<td style=\"width: 20%; text-align: center;\">637<br \/>\n(637)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">693<br \/>\n(713)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25219<br \/>\n(28219)<\/td>\n<td style=\"width: 20%; text-align: center;\">701<br \/>\n(721)<\/td>\n<td style=\"width: 20%; text-align: center;\">649<br \/>\n(649)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">709<br \/>\n(729)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26224<br \/>\n(29224)<\/td>\n<td style=\"width: 20%; text-align: center;\">721<br \/>\n(741)<\/td>\n<td style=\"width: 20%; text-align: center;\">664<br \/>\n(664)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">729<br \/>\n(749)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27649<br \/>\n(30649)<\/td>\n<td style=\"width: 20%; text-align: center;\">751<br \/>\n(771)<\/td>\n<td style=\"width: 20%; text-align: center;\">685<br \/>\n(685)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">759<br \/>\n(779)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23849<br \/>\n(26849)<\/td>\n<td style=\"width: 20%; text-align: center;\">672<br \/>\n(692)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">682<br \/>\n(702)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24659<br \/>\n(27659)<\/td>\n<td style=\"width: 20%; text-align: center;\">688<br \/>\n(708)<\/td>\n<td style=\"width: 20%; text-align: center;\">638<br \/>\n(638)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">698<br \/>\n(718)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25469<br \/>\n(28469)<\/td>\n<td style=\"width: 20%; text-align: center;\">704<br \/>\n(724)<\/td>\n<td style=\"width: 20%; text-align: center;\">650<br \/>\n(650)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">714<br \/>\n(734)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26474<br \/>\n(29474)<\/td>\n<td style=\"width: 20%; text-align: center;\">724<br \/>\n(744)<\/td>\n<td style=\"width: 20%; text-align: center;\">665<br \/>\n(665)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">734<br \/>\n(754)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27899<br \/>\n(30899)<\/td>\n<td style=\"width: 20%; text-align: center;\">754<br \/>\n(774)<\/td>\n<td style=\"width: 20%; text-align: center;\">686<br \/>\n(686)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">764<br \/>\n(784)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24119<br \/>\n(27119)<\/td>\n<td style=\"width: 20%; text-align: center;\">675<br \/>\n(695)<\/td>\n<td style=\"width: 20%; text-align: center;\">628<br \/>\n(628)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">687<br \/>\n(707)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24929<br \/>\n(27929)<\/td>\n<td style=\"width: 20%; text-align: center;\">691<br \/>\n(711)<\/td>\n<td style=\"width: 20%; text-align: center;\">640<br \/>\n(640)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">703<br \/>\n(723)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25739<br \/>\n(28739)<\/td>\n<td style=\"width: 20%; text-align: center;\">707<br \/>\n(727)<\/td>\n<td style=\"width: 20%; text-align: center;\">652<br \/>\n(652)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">719<br \/>\n(739)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26744<br \/>\n(29744)<\/td>\n<td style=\"width: 20%; text-align: center;\">727<br \/>\n(747)<\/td>\n<td style=\"width: 20%; text-align: center;\">667<br \/>\n(667)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">739<br \/>\n(759)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28169<br \/>\n(31169)<\/td>\n<td style=\"width: 20%; text-align: center;\">757<br \/>\n(777)<\/td>\n<td style=\"width: 20%; text-align: center;\">688<br \/>\n(688)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">769<br \/>\n(789)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<div id=\"FD2\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD2-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-2\"><li class=\"active\"><a class=\"\" href=\"#pane-2-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-2-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21889<br \/>\n(24389)<\/td>\n<td style=\"width: 20%; text-align: center;\">609<br \/>\n(609)<\/td>\n<td style=\"width: 20%; text-align: center;\">592<br \/>\n(602)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">701<br \/>\n(731)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22699<br \/>\n(25199)<\/td>\n<td style=\"width: 20%; text-align: center;\">625<br \/>\n(625)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(614)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">717<br \/>\n(747)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23509<br \/>\n(26009)<\/td>\n<td style=\"width: 20%; text-align: center;\">641<br \/>\n(641)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">733<br \/>\n(763)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24514<br \/>\n(27014)<\/td>\n<td style=\"width: 20%; text-align: center;\">661<br \/>\n(661)<\/td>\n<td style=\"width: 20%; text-align: center;\">631<br \/>\n(641)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">753<br \/>\n(783)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25939<br \/>\n(28439)<\/td>\n<td style=\"width: 20%; text-align: center;\">691<br \/>\n(691)<\/td>\n<td style=\"width: 20%; text-align: center;\">652<br \/>\n(662)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">783<br \/>\n(813)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22409<br \/>\n(24909)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(618)<\/td>\n<td style=\"width: 20%; text-align: center;\">599<br \/>\n(609)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">712<br \/>\n(742)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23219<br \/>\n(25719)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(634)<\/td>\n<td style=\"width: 20%; text-align: center;\">611<br \/>\n(621)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">728<br \/>\n(758)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24029<br \/>\n(26529)<\/td>\n<td style=\"width: 20%; text-align: center;\">650<br \/>\n(650)<\/td>\n<td style=\"width: 20%; text-align: center;\">623<br \/>\n(633)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">744<br \/>\n(774)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25034<br \/>\n(27534)<\/td>\n<td style=\"width: 20%; text-align: center;\">670<br \/>\n(670)<\/td>\n<td style=\"width: 20%; text-align: center;\">638<br \/>\n(648)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">764<br \/>\n(794)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26459<br \/>\n(28959)<\/td>\n<td style=\"width: 20%; text-align: center;\">700<br \/>\n(700)<\/td>\n<td style=\"width: 20%; text-align: center;\">659<br \/>\n(669)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">794<br \/>\n(824)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22564<br \/>\n(25064)<\/td>\n<td style=\"width: 20%; text-align: center;\">619<br \/>\n(619)<\/td>\n<td style=\"width: 20%; text-align: center;\">600<br \/>\n(610)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">715<br \/>\n(745)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23374<br \/>\n(25874)<\/td>\n<td style=\"width: 20%; text-align: center;\">635<br \/>\n(635)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(622)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">731<br \/>\n(761)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24184<br \/>\n(26684)<\/td>\n<td style=\"width: 20%; text-align: center;\">651<br \/>\n(651)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(634)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">747<br \/>\n(777)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25189<br \/>\n(27689)<\/td>\n<td style=\"width: 20%; text-align: center;\">671<br \/>\n(671)<\/td>\n<td style=\"width: 20%; text-align: center;\">639<br \/>\n(649)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">767<br \/>\n(797)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26614<br \/>\n(29114)<\/td>\n<td style=\"width: 20%; text-align: center;\">701<br \/>\n(701)<\/td>\n<td style=\"width: 20%; text-align: center;\">660<br \/>\n(670)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">797<br \/>\n(827)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22744<br \/>\n(25244)<\/td>\n<td style=\"width: 20%; text-align: center;\">621<br \/>\n(621)<\/td>\n<td style=\"width: 20%; text-align: center;\">601<br \/>\n(611)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">719<br \/>\n(749)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23554<br \/>\n(26054)<\/td>\n<td style=\"width: 20%; text-align: center;\">637<br \/>\n(637)<\/td>\n<td style=\"width: 20%; text-align: center;\">613<br \/>\n(623)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">735<br \/>\n(765)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24364<br \/>\n(26864)<\/td>\n<td style=\"width: 20%; text-align: center;\">653<br \/>\n(653)<\/td>\n<td style=\"width: 20%; text-align: center;\">625<br \/>\n(635)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">751<br \/>\n(781)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25369<br \/>\n(27869)<\/td>\n<td style=\"width: 20%; text-align: center;\">673<br \/>\n(673)<\/td>\n<td style=\"width: 20%; text-align: center;\">640<br \/>\n(650)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">771<br \/>\n(801)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26794<br \/>\n(29294)<\/td>\n<td style=\"width: 20%; text-align: center;\">703<br \/>\n(703)<\/td>\n<td style=\"width: 20%; text-align: center;\">661<br \/>\n(671)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">801<br \/>\n(831)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22934<br \/>\n(25434)<\/td>\n<td style=\"width: 20%; text-align: center;\">623<br \/>\n(623)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(612)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">723<br \/>\n(753)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23744<br \/>\n(26244)<\/td>\n<td style=\"width: 20%; text-align: center;\">639<br \/>\n(639)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">739<br \/>\n(769)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24554<br \/>\n(27054)<\/td>\n<td style=\"width: 20%; text-align: center;\">655<br \/>\n(655)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(636)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">755<br \/>\n(785)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25559<br \/>\n(28059)<\/td>\n<td style=\"width: 20%; text-align: center;\">675<br \/>\n(675)<\/td>\n<td style=\"width: 20%; text-align: center;\">641<br \/>\n(651)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">775<br \/>\n(805)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26984<br \/>\n(29484)<\/td>\n<td style=\"width: 20%; text-align: center;\">705<br \/>\n(705)<\/td>\n<td style=\"width: 20%; text-align: center;\">662<br \/>\n(672)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">805<br \/>\n(835)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23139<br \/>\n(25639)<\/td>\n<td style=\"width: 20%; text-align: center;\">625<br \/>\n(625)<\/td>\n<td style=\"width: 20%; text-align: center;\">603<br \/>\n(613)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">727<br \/>\n(757)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23949<br \/>\n(26449)<\/td>\n<td style=\"width: 20%; text-align: center;\">641<br \/>\n(641)<\/td>\n<td style=\"width: 20%; text-align: center;\">615<br \/>\n(625)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">743<br \/>\n(773)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24759<br \/>\n(27259)<\/td>\n<td style=\"width: 20%; text-align: center;\">657<br \/>\n(657)<\/td>\n<td style=\"width: 20%; text-align: center;\">627<br \/>\n(637)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">759<br \/>\n(789)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25764<br \/>\n(28264)<\/td>\n<td style=\"width: 20%; text-align: center;\">677<br \/>\n(677)<\/td>\n<td style=\"width: 20%; text-align: center;\">642<br \/>\n(652)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">779<br \/>\n(809)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27189<br \/>\n(29689)<\/td>\n<td style=\"width: 20%; text-align: center;\">707<br \/>\n(707)<\/td>\n<td style=\"width: 20%; text-align: center;\">663<br \/>\n(673)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">809<br \/>\n(839)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23364<br \/>\n(25864)<\/td>\n<td style=\"width: 20%; text-align: center;\">627<br \/>\n(627)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(614)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">732<br \/>\n(762)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24174<br \/>\n(26674)<\/td>\n<td style=\"width: 20%; text-align: center;\">643<br \/>\n(643)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">748<br \/>\n(778)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24984<br \/>\n(27484)<\/td>\n<td style=\"width: 20%; text-align: center;\">659<br \/>\n(659)<\/td>\n<td style=\"width: 20%; text-align: center;\">628<br \/>\n(638)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">764<br \/>\n(794)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25989<br \/>\n(28489)<\/td>\n<td style=\"width: 20%; text-align: center;\">679<br \/>\n(679)<\/td>\n<td style=\"width: 20%; text-align: center;\">643<br \/>\n(653)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">784<br \/>\n(814)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27414<br \/>\n(29914)<\/td>\n<td style=\"width: 20%; text-align: center;\">709<br \/>\n(709)<\/td>\n<td style=\"width: 20%; text-align: center;\">664<br \/>\n(674)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">814<br \/>\n(844)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23599<br \/>\n(26099)<\/td>\n<td style=\"width: 20%; text-align: center;\">629<br \/>\n(629)<\/td>\n<td style=\"width: 20%; text-align: center;\">605<br \/>\n(615)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">737<br \/>\n(767)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24409<br \/>\n(26909)<\/td>\n<td style=\"width: 20%; text-align: center;\">645<br \/>\n(645)<\/td>\n<td style=\"width: 20%; text-align: center;\">617<br \/>\n(627)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">753<br \/>\n(783)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25219<br \/>\n(27719)<\/td>\n<td style=\"width: 20%; text-align: center;\">661<br \/>\n(661)<\/td>\n<td style=\"width: 20%; text-align: center;\">629<br \/>\n(639)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">769<br \/>\n(799)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26224<br \/>\n(28724)<\/td>\n<td style=\"width: 20%; text-align: center;\">681<br \/>\n(681)<\/td>\n<td style=\"width: 20%; text-align: center;\">644<br \/>\n(654)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">789<br \/>\n(819)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27649<br \/>\n(30149)<\/td>\n<td style=\"width: 20%; text-align: center;\">711<br \/>\n(711)<\/td>\n<td style=\"width: 20%; text-align: center;\">665<br \/>\n(675)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">819<br \/>\n(849)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23849<br \/>\n(26349)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(632)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(616)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">742<br \/>\n(772)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24659<br \/>\n(27159)<\/td>\n<td style=\"width: 20%; text-align: center;\">648<br \/>\n(648)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(628)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">758<br \/>\n(788)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25469<br \/>\n(27969)<\/td>\n<td style=\"width: 20%; text-align: center;\">664<br \/>\n(664)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(640)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">774<br \/>\n(804)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26474<br \/>\n(28974)<\/td>\n<td style=\"width: 20%; text-align: center;\">684<br \/>\n(684)<\/td>\n<td style=\"width: 20%; text-align: center;\">645<br \/>\n(655)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">794<br \/>\n(824)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27899<br \/>\n(30399)<\/td>\n<td style=\"width: 20%; text-align: center;\">714<br \/>\n(714)<\/td>\n<td style=\"width: 20%; text-align: center;\">666<br \/>\n(676)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">824<br \/>\n(854)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24119<br \/>\n(26619)<\/td>\n<td style=\"width: 20%; text-align: center;\">635<br \/>\n(635)<\/td>\n<td style=\"width: 20%; text-align: center;\">608<br \/>\n(618)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">747<br \/>\n(777)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24929<br \/>\n(27429)<\/td>\n<td style=\"width: 20%; text-align: center;\">651<br \/>\n(651)<\/td>\n<td style=\"width: 20%; text-align: center;\">620<br \/>\n(630)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">763<br \/>\n(793)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25739<br \/>\n(28239)<\/td>\n<td style=\"width: 20%; text-align: center;\">667<br \/>\n(667)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(642)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">779<br \/>\n(809)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26744<br \/>\n(29244)<\/td>\n<td style=\"width: 20%; text-align: center;\">687<br \/>\n(687)<\/td>\n<td style=\"width: 20%; text-align: center;\">647<br \/>\n(657)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">799<br \/>\n(829)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28169<br \/>\n(30669)<\/td>\n<td style=\"width: 20%; text-align: center;\">717<br \/>\n(717)<\/td>\n<td style=\"width: 20%; text-align: center;\">668<br \/>\n(678)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">829<br \/>\n(859)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<p><span style=\"color: #ff0000; font-size: 10pt;\">\u2022The number between () indicates the stat value at maximum Type Boost<\/span><\/p>\n<h2 class=\"sexypurple\" style=\"text-align: center;\">\nNormal Attack<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-3\"><li class=\"active\"><a class=\"\" href=\"#pane-3-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-3-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-3-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-3-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 1: Shot (\u9283\u6483)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">77 (100)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">None<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 2: Thorns Shot (\u68d8\u9283\u6483)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">116 (150)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">3<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">50% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_1\"> Severe Pain <\/button><div id=\"osc_popover_1\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-3-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 1: Shot (\u9283\u6483)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">77 (100)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">None<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 2: Thorns Shot (\u68d8\u9283\u6483)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">116 (150)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">3<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">50% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_2\"> Severe Pain <\/button><div id=\"osc_popover_2\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-3-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 1: Shot (\u9283\u6483)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">77 (100)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">None<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 2: Thorns Shot (\u68d8\u9283\u6483)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">116 (150)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">3<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">50% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_3\"> Severe Pain <\/button><div id=\"osc_popover_3\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<h2 class=\"sexyblue\" style=\"text-align: center;\">\nSkills<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-4\"><li class=\"active\"><a class=\"\" href=\"#pane-4-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-4-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-4-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-4-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Rosenkugel EX (\u30ed\u30fc\u30bc\u30f3\u30af\u30fc\u30b2\u30ebEX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">177 (230)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">3<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td style=\"vertical-align: middle;\" colspan=\"3\">\n<p>[Super Fastest]<\/p>\n<ol>\n<li>Inflict the target with<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Disable\" data-contentwrapper=\"osc_popover_4\"> Disable <\/button><div id=\"osc_popover_4\" style=\"display:none;\">Disable the character from doing any action<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    (1 turn) <span style=\"color: #ff0000; font-size: 10pt;\">\u203b This effect cannot be extended<\/span><\/li>\n<li>After the attack go into a 154 (200) power<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Quick Charge\" data-contentwrapper=\"osc_popover_5\"> Quick Charge <\/button><div id=\"osc_popover_5\" style=\"display:none;\">Attack All Enemies at the end of the turn<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>While in<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Quick Charge\" data-contentwrapper=\"osc_popover_6\"> Quick Charge <\/button><div id=\"osc_popover_6\" style=\"display:none;\">Attack All Enemies at the end of the turn<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    increase own evasion by 70%<\/li>\n<\/ol>\n<p>Cool-down: 4 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Edel Dornburg EX (\u30a8\u30fc\u30c7\u30eb\u30c9\u30eb\u30f3\u30d6\u30eb\u30afEX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">193 (250)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">5<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>80% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_7\"> Severe Pain <\/button><div id=\"osc_popover_7\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>Increase attack of All Allies by 30% (2 turns)<\/li>\n<li>Apply 20%<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Reduction (EB)\" data-contentwrapper=\"osc_popover_8\"> Damage Reduction (EB) <\/button><div id=\"osc_popover_8\" style=\"display:none;\">Reduces damage taken from Elemental Blasts<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    to All Allies (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-4-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Rosenkugel [Weak Hit Type] EX (\u30ed\u30fc\u30bc\u30f3\u30af\u30fc\u30b2\u30eb[\u7834]EX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">131 (170)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">3<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"vertical-align: middle; width: 75%;\" colspan=\"3\">\n<p>[Super Fastest]<\/p>\n<ol>\n<li>Reduce Target attack, speed and defense by 10% (2 turns)<\/li>\n<li>50% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_9\"> Severe Pain <\/button><div id=\"osc_popover_9\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>After the attack go into a 139 (180) power<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Quick Charge\" data-contentwrapper=\"osc_popover_10\"> Quick Charge <\/button><div id=\"osc_popover_10\" style=\"display:none;\">Attack All Enemies at the end of the turn<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<\/ol>\n<p>Cool-down: 4 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Edel Dornburg [Critical Hit Type] EX (\u30a8\u30fc\u30c7\u30eb\u30c9\u30eb\u30f3\u30d6\u30eb\u30af[\u6280]EX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">193 (250)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">5<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>80% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_11\"> Severe Pain <\/button><div id=\"osc_popover_11\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>Reduce Target defense by 20% (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-4-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Rosenkugel [Critical Hit Type] EX (\u30ed\u30fc\u30bc\u30f3\u30af\u30fc\u30b2\u30eb[\u6280]EX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">147 (190)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">2<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"vertical-align: middle; width: 75%;\" colspan=\"3\">\n<p>[Super Fastest]<\/p>\n<ol>\n<li>Inflict the target with<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Disable\" data-contentwrapper=\"osc_popover_12\"> Disable <\/button><div id=\"osc_popover_12\" style=\"display:none;\">Disable the character from doing any action<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    (1 turn) <span style=\"color: #ff0000; font-size: 10pt;\">\u203b This effect cannot be extended<\/span><\/li>\n<li>After the attack go into a 139 (180) power<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Quick Charge\" data-contentwrapper=\"osc_popover_13\"> Quick Charge <\/button><div id=\"osc_popover_13\" style=\"display:none;\">Attack All Enemies at the end of the turn<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>While in<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Quick Charge\" data-contentwrapper=\"osc_popover_14\"> Quick Charge <\/button><div id=\"osc_popover_14\" style=\"display:none;\">Attack All Enemies at the end of the turn<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    increase own evasion by 30%<\/li>\n<\/ol>\n<p>Cool-down: 4 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Edel Dornburg [Critical Hit Type] EX (\u30a8\u30fc\u30c7\u30eb\u30c9\u30eb\u30f3\u30d6\u30eb\u30af[\u7834]EX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">193 (250)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">4<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>80% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_15\"> Severe Pain <\/button><div id=\"osc_popover_15\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>Apply 20%<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Reduction (EB)\" data-contentwrapper=\"osc_popover_16\"> Damage Reduction (EB) <\/button><div id=\"osc_popover_16\" style=\"display:none;\">Reduces damage taken from Elemental Blasts<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    to All Allies (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<h2 class=\"sexyred\" style=\"text-align: center;\">\nElemental Blast<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-5\"><li class=\"active\"><a class=\"\" href=\"#pane-5-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-5-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-5-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-5-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Sentiment Bloom EX (\u30bb\u30f3\u30c6\u30a3\u30c3\u30c9\u30d6\u30eb\u30fc\u30e0EX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">378 (530)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">7<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">7<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td colspan=\"3\">\n<p>[Super Fastest]<\/p>\n<ol>\n<li>Inflict the target with<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Disable\" data-contentwrapper=\"osc_popover_17\"> Disable <\/button><div id=\"osc_popover_17\" style=\"display:none;\">Disable the character from doing any action<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    (1 turn) <span style=\"color: #ff0000; font-size: 10pt;\">\u203b This effect cannot be extended<\/span><\/li>\n<li>Reduce own skill cooldowns by 5 turns<\/li>\n<li>If the Target is inflicted with<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_18\"> Severe Pain <\/button><div id=\"osc_popover_18\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    increase damage dealt by 50%<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-5-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Sentiment Bloom [Weak Hit Type] EX (\u30bb\u30f3\u30c6\u30a3\u30c3\u30c9\u30d6\u30eb\u30fc\u30e0[\u7834]EX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">378 (530)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">7<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">7<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<p>[Super Fastest]<\/p>\n<ol>\n<li>If the Target is in<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_19\"> Severe Pain <\/button><div id=\"osc_popover_19\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    inflict the target with<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Disable\" data-contentwrapper=\"osc_popover_20\"> Disable <\/button><div id=\"osc_popover_20\" style=\"display:none;\">Disable the character from doing any action<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    (2 turns) <span style=\"color: #ff0000; font-size: 10pt;\">\u203b This effect cannot be extended<\/span><\/li>\n<li>Reduce own skill cooldowns by 5 turns<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-5-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Sentiment Bloom [Critical Hit Type] EX (\u30bb\u30f3\u30c6\u30a3\u30c3\u30c9\u30d6\u30eb\u30fc\u30e0[\u7834]EX)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">300 (420)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">6<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">6<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<p>[Super Fastest]<\/p>\n<ol>\n<li>Inflict the target with<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Disable\" data-contentwrapper=\"osc_popover_21\"> Disable <\/button><div id=\"osc_popover_21\" style=\"display:none;\">Disable the character from doing any action<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    (1 turn) <span style=\"color: #ff0000; font-size: 10pt;\">\u203b This effect cannot be extended<\/span><\/li>\n<li>Reduce own skill cooldowns by 5 turns<\/li>\n<li>If the Target is inflicted with<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Severe Pain\" data-contentwrapper=\"osc_popover_22\"> Severe Pain <\/button><div id=\"osc_popover_22\" style=\"display:none;\">Character takes damage when attacking<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    increase damage dealt by 50%<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&lt; Back to Characters &nbsp; Odette [EX] (Law) Weak Hit Type Odette [EX] Attack Type Odette [EX] (Chaos) Critical Hit Type Rarity Faction Chaos Class Shooter Element \u00a0Fire Idola Hydra Fates Law Chaos Date 2021\/10\/26 Race Demonic Character Stats Default Law Chaos \u2022The number between () indicates the stat value at maximum Type Boost Normal [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":567,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-8998","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PatEj8-2l8","_links":{"self":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/8998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/comments?post=8998"}],"version-history":[{"count":2,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/8998\/revisions"}],"predecessor-version":[{"id":9007,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/8998\/revisions\/9007"}],"up":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/567"}],"wp:attachment":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/media?parent=8998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}