{"id":8151,"date":"2021-04-27T06:28:06","date_gmt":"2021-04-27T10:28:06","guid":{"rendered":"https:\/\/bumped.org\/idola\/?page_id=8151"},"modified":"2021-07-28T10:17:42","modified_gmt":"2021-07-28T14:17:42","slug":"character-giselle-memories","status":"publish","type":"page","link":"https:\/\/bumped.org\/idola\/idola-character-database\/character-giselle-memories\/","title":{"rendered":"Character: Giselle [Memories]"},"content":{"rendered":"<p><a href=\"https:\/\/bumped.org\/idola\/idola-character-database\/\">&lt; Back to Characters<\/a><\/p>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-law.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8152\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-law.png?resize=440%2C440&#038;ssl=1\" alt=\"\" width=\"440\" height=\"440\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-law.png?w=440&amp;ssl=1 440w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-law.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-law.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-law.png?resize=60%2C60&amp;ssl=1 60w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/td>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8153\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories.png?resize=440%2C440&#038;ssl=1\" alt=\"\" width=\"440\" height=\"440\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories.png?w=440&amp;ssl=1 440w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories.png?resize=60%2C60&amp;ssl=1 60w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/td>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-chaos.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8155\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-chaos.png?resize=440%2C440&#038;ssl=1\" alt=\"\" width=\"440\" height=\"440\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-chaos.png?w=440&amp;ssl=1 440w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-chaos.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-chaos.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/04\/character-giselle-memories-chaos.png?resize=60%2C60&amp;ssl=1 60w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 33.3333%; text-align: center;\">\n<p>Giselle [Memories] (Law)<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-defense.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5888\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-defense.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Defense Type<\/p>\n<\/th>\n<th style=\"width: 33.3333%; text-align: center;\">Giselle [Memories]<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-weak-hit-damage.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5886\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-weak-hit-damage.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Weak Hit Type<\/th>\n<th style=\"width: 33.3333%; text-align: center;\">Giselle [Memories] (Chaos)<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-attack.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-5889 alignnone\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-attack.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Attack Type<\/th>\n<\/tr>\n<\/tbody>\n<\/table>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 100%; border-color: #757575;\" border=\"1\" width=\"100%\">\n<thead>\n<tr>\n<td style=\"background-color: #e3e3e3; width: 20%; border-color: grey; text-align: center; vertical-align: middle;\" width=\"20%\">Rarity<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\" width=\"30%\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; width: 20%; text-align: center; vertical-align: middle;\" width=\"20%\">Faction<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\" width=\"30%\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1280\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Chaos-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Chaos<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"border-color: #757575;\">\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Class<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">Striker<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Element<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1069\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/element-icon-earth-e1543536670823.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Earth<\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Idola<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1079\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/idola-icon-7-e1543537574755.png?resize=17%2C22&#038;ssl=1\" alt=\"\" width=\"17\" height=\"22\" \/> Andromeda G Type<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Fates<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1281\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Law-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Law<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1280\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Chaos-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Chaos<\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Date<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">2021\/04\/27<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Race<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">Human<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"sexyblue\" style=\"text-align: center;\">Character Stats<\/h2>\n<ul id=\"DBLimits\" class=\"nav nav-tabs\" role=\"tablist\">\n<li class=\"nav-item\"><a id=\"limi0-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD0\" data-toggle=\"tab\">Default<\/a><\/li>\n<li class=\"nav-item\"><a id=\"limi1-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD1\" data-toggle=\"tab\">Law<\/a><\/li>\n<li class=\"nav-item\"><a id=\"limi2-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD2\" data-toggle=\"tab\">Chaos<\/a><\/li>\n<\/ul>\n<div id=\"DBStats\" class=\"tab-content small\">\n<div id=\"FD0\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD0-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-0\"><li class=\"active\"><a class=\"\" href=\"#pane-0-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-0-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23676<br \/>\n(26676)<\/td>\n<td style=\"width: 20%; text-align: center;\">676<br \/>\n(696)<\/td>\n<td style=\"width: 20%; text-align: center;\">701<br \/>\n(701)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">582<br \/>\n(602)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24216<br \/>\n(27216)<\/td>\n<td style=\"width: 20%; text-align: center;\">688<br \/>\n(708)<\/td>\n<td style=\"width: 20%; text-align: center;\">709<br \/>\n(709)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">592<br \/>\n(612)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24756<br \/>\n(27756)<\/td>\n<td style=\"width: 20%; text-align: center;\">700<br \/>\n(720)<\/td>\n<td style=\"width: 20%; text-align: center;\">717<br \/>\n(717)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">602<br \/>\n(622)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25426<br \/>\n(28426)<\/td>\n<td style=\"width: 20%; text-align: center;\">714<br \/>\n(734)<\/td>\n<td style=\"width: 20%; text-align: center;\">727<br \/>\n(727)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">614<br \/>\n(634)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26376<br \/>\n(29376)<\/td>\n<td style=\"width: 20%; text-align: center;\">736<br \/>\n(756)<\/td>\n<td style=\"width: 20%; text-align: center;\">741<br \/>\n(741)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">632<br \/>\n(652)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24186<br \/>\n(27186)<\/td>\n<td style=\"width: 20%; text-align: center;\">685<br \/>\n(705)<\/td>\n<td style=\"width: 20%; text-align: center;\">710<br \/>\n(710)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">591<br \/>\n(611)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24726<br \/>\n(27726)<\/td>\n<td style=\"width: 20%; text-align: center;\">697<br \/>\n(717)<\/td>\n<td style=\"width: 20%; text-align: center;\">718<br \/>\n(718)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">601<br \/>\n(621)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25266<br \/>\n(28266)<\/td>\n<td style=\"width: 20%; text-align: center;\">709<br \/>\n(729)<\/td>\n<td style=\"width: 20%; text-align: center;\">726<br \/>\n(726)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">611<br \/>\n(631)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25936<br \/>\n(28936)<\/td>\n<td style=\"width: 20%; text-align: center;\">723<br \/>\n(743)<\/td>\n<td style=\"width: 20%; text-align: center;\">736<br \/>\n(736)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">623<br \/>\n(643)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26886<br \/>\n(29886)<\/td>\n<td style=\"width: 20%; text-align: center;\">745<br \/>\n(765)<\/td>\n<td style=\"width: 20%; text-align: center;\">750<br \/>\n(750)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">641<br \/>\n(661)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24366<br \/>\n(27366)<\/td>\n<td style=\"width: 20%; text-align: center;\">687<br \/>\n(707)<\/td>\n<td style=\"width: 20%; text-align: center;\">712<br \/>\n(712)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">592<br \/>\n(612)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24906<br \/>\n(27906)<\/td>\n<td style=\"width: 20%; text-align: center;\">699<br \/>\n(719)<\/td>\n<td style=\"width: 20%; text-align: center;\">720<br \/>\n(720)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">602<br \/>\n(622)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25446<br \/>\n(28446)<\/td>\n<td style=\"width: 20%; text-align: center;\">711<br \/>\n(731)<\/td>\n<td style=\"width: 20%; text-align: center;\">728<br \/>\n(728)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">612<br \/>\n(632)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26116<br \/>\n(29116)<\/td>\n<td style=\"width: 20%; text-align: center;\">725<br \/>\n(745)<\/td>\n<td style=\"width: 20%; text-align: center;\">738<br \/>\n(738)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">624<br \/>\n(644)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27066<br \/>\n(30066)<\/td>\n<td style=\"width: 20%; text-align: center;\">747<br \/>\n(767)<\/td>\n<td style=\"width: 20%; text-align: center;\">752<br \/>\n(752)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">642<br \/>\n(662)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24561<br \/>\n(27561)<\/td>\n<td style=\"width: 20%; text-align: center;\">689<br \/>\n(709)<\/td>\n<td style=\"width: 20%; text-align: center;\">714<br \/>\n(714)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">594<br \/>\n(614)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25101<br \/>\n(28101)<\/td>\n<td style=\"width: 20%; text-align: center;\">701<br \/>\n(721)<\/td>\n<td style=\"width: 20%; text-align: center;\">722<br \/>\n(722)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">604<br \/>\n(624)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25641<br \/>\n(28641)<\/td>\n<td style=\"width: 20%; text-align: center;\">713<br \/>\n(733)<\/td>\n<td style=\"width: 20%; text-align: center;\">730<br \/>\n(730)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">614<br \/>\n(634)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26311<br \/>\n(29311)<\/td>\n<td style=\"width: 20%; text-align: center;\">727<br \/>\n(747)<\/td>\n<td style=\"width: 20%; text-align: center;\">740<br \/>\n(740)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">626<br \/>\n(646)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27261<br \/>\n(30261)<\/td>\n<td style=\"width: 20%; text-align: center;\">749<br \/>\n(769)<\/td>\n<td style=\"width: 20%; text-align: center;\">754<br \/>\n(754)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">644<br \/>\n(664)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24766<br \/>\n(27766)<\/td>\n<td style=\"width: 20%; text-align: center;\">692<br \/>\n(712)<\/td>\n<td style=\"width: 20%; text-align: center;\">717<br \/>\n(717)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">596<br \/>\n(616)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25306<br \/>\n(28306)<\/td>\n<td style=\"width: 20%; text-align: center;\">704<br \/>\n(724)<\/td>\n<td style=\"width: 20%; text-align: center;\">725<br \/>\n(725)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">606<br \/>\n(626)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25846<br \/>\n(28846)<\/td>\n<td style=\"width: 20%; text-align: center;\">716<br \/>\n(736)<\/td>\n<td style=\"width: 20%; text-align: center;\">733<br \/>\n(733)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">616<br \/>\n(636)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26516<br \/>\n(29516)<\/td>\n<td style=\"width: 20%; text-align: center;\">730<br \/>\n(750)<\/td>\n<td style=\"width: 20%; text-align: center;\">743<br \/>\n(743)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">628<br \/>\n(648)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27466<br \/>\n(30466)<\/td>\n<td style=\"width: 20%; text-align: center;\">752<br \/>\n(772)<\/td>\n<td style=\"width: 20%; text-align: center;\">757<br \/>\n(757)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">646<br \/>\n(666)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24981<br \/>\n(27981)<\/td>\n<td style=\"width: 20%; text-align: center;\">694<br \/>\n(714)<\/td>\n<td style=\"width: 20%; text-align: center;\">719<br \/>\n(719)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">598<br \/>\n(618)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25521<br \/>\n(28521)<\/td>\n<td style=\"width: 20%; text-align: center;\">706<br \/>\n(726)<\/td>\n<td style=\"width: 20%; text-align: center;\">727<br \/>\n(727)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">608<br \/>\n(628)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26061<br \/>\n(29061)<\/td>\n<td style=\"width: 20%; text-align: center;\">718<br \/>\n(738)<\/td>\n<td style=\"width: 20%; text-align: center;\">735<br \/>\n(735)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">618<br \/>\n(638)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26731<br \/>\n(29731)<\/td>\n<td style=\"width: 20%; text-align: center;\">732<br \/>\n(752)<\/td>\n<td style=\"width: 20%; text-align: center;\">745<br \/>\n(745)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">630<br \/>\n(650)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27681<br \/>\n(30681)<\/td>\n<td style=\"width: 20%; text-align: center;\">754<br \/>\n(774)<\/td>\n<td style=\"width: 20%; text-align: center;\">759<br \/>\n(759)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">648<br \/>\n(668)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25211<br \/>\n(28211)<\/td>\n<td style=\"width: 20%; text-align: center;\">697<br \/>\n(717)<\/td>\n<td style=\"width: 20%; text-align: center;\">722<br \/>\n(722)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">600<br \/>\n(620)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25751<br \/>\n(28751)<\/td>\n<td style=\"width: 20%; text-align: center;\">709<br \/>\n(729)<\/td>\n<td style=\"width: 20%; text-align: center;\">730<br \/>\n(730)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">610<br \/>\n(630)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26291<br \/>\n(29291)<\/td>\n<td style=\"width: 20%; text-align: center;\">721<br \/>\n(741)<\/td>\n<td style=\"width: 20%; text-align: center;\">738<br \/>\n(738)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">620<br \/>\n(640)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26961<br \/>\n(29961)<\/td>\n<td style=\"width: 20%; text-align: center;\">735<br \/>\n(755)<\/td>\n<td style=\"width: 20%; text-align: center;\">748<br \/>\n(748)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">632<br \/>\n(652)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27911<br \/>\n(30911)<\/td>\n<td style=\"width: 20%; text-align: center;\">757<br \/>\n(777)<\/td>\n<td style=\"width: 20%; text-align: center;\">762<br \/>\n(762)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">650<br \/>\n(670)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25451<br \/>\n(28451)<\/td>\n<td style=\"width: 20%; text-align: center;\">700<br \/>\n(720)<\/td>\n<td style=\"width: 20%; text-align: center;\">725<br \/>\n(725)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">602<br \/>\n(622)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25991<br \/>\n(28991)<\/td>\n<td style=\"width: 20%; text-align: center;\">712<br \/>\n(732)<\/td>\n<td style=\"width: 20%; text-align: center;\">733<br \/>\n(733)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">612<br \/>\n(632)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26531<br \/>\n(29531)<\/td>\n<td style=\"width: 20%; text-align: center;\">724<br \/>\n(744)<\/td>\n<td style=\"width: 20%; text-align: center;\">741<br \/>\n(741)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">622<br \/>\n(642)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27201<br \/>\n(30201)<\/td>\n<td style=\"width: 20%; text-align: center;\">738<br \/>\n(758)<\/td>\n<td style=\"width: 20%; text-align: center;\">751<br \/>\n(751)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">634<br \/>\n(654)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28151<br \/>\n(31151)<\/td>\n<td style=\"width: 20%; text-align: center;\">760<br \/>\n(780)<\/td>\n<td style=\"width: 20%; text-align: center;\">765<br \/>\n(765)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">652<br \/>\n(672)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25711<br \/>\n(28711)<\/td>\n<td style=\"width: 20%; text-align: center;\">703<br \/>\n(723)<\/td>\n<td style=\"width: 20%; text-align: center;\">728<br \/>\n(728)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">605<br \/>\n(625)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26251<br \/>\n(29251)<\/td>\n<td style=\"width: 20%; text-align: center;\">715<br \/>\n(735)<\/td>\n<td style=\"width: 20%; text-align: center;\">736<br \/>\n(736)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">615<br \/>\n(635)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26791<br \/>\n(29791)<\/td>\n<td style=\"width: 20%; text-align: center;\">727<br \/>\n(747)<\/td>\n<td style=\"width: 20%; text-align: center;\">744<br \/>\n(744)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">625<br \/>\n(645)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27461<br \/>\n(30461)<\/td>\n<td style=\"width: 20%; text-align: center;\">741<br \/>\n(761)<\/td>\n<td style=\"width: 20%; text-align: center;\">754<br \/>\n(754)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">637<br \/>\n(657)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28411<br \/>\n(31411)<\/td>\n<td style=\"width: 20%; text-align: center;\">763<br \/>\n(783)<\/td>\n<td style=\"width: 20%; text-align: center;\">768<br \/>\n(768)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">655<br \/>\n(675)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25996<br \/>\n(28996)<\/td>\n<td style=\"width: 20%; text-align: center;\">707<br \/>\n(727)<\/td>\n<td style=\"width: 20%; text-align: center;\">732<br \/>\n(732)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">608<br \/>\n(628)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26536<br \/>\n(29536)<\/td>\n<td style=\"width: 20%; text-align: center;\">719<br \/>\n(739)<\/td>\n<td style=\"width: 20%; text-align: center;\">740<br \/>\n(740)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">618<br \/>\n(638)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">27076<br \/>\n(30076)<\/td>\n<td style=\"width: 20%; text-align: center;\">731<br \/>\n(751)<\/td>\n<td style=\"width: 20%; text-align: center;\">748<br \/>\n(748)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">628<br \/>\n(648)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27746<br \/>\n(30746)<\/td>\n<td style=\"width: 20%; text-align: center;\">745<br \/>\n(765)<\/td>\n<td style=\"width: 20%; text-align: center;\">758<br \/>\n(758)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">640<br \/>\n(660)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28696<br \/>\n(31696)<\/td>\n<td style=\"width: 20%; text-align: center;\">767<br \/>\n(787)<\/td>\n<td style=\"width: 20%; text-align: center;\">772<br \/>\n(772)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">658<br \/>\n(678)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<div id=\"FD1\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD1-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-1\"><li class=\"active\"><a class=\"\" href=\"#pane-1-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-1-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24076<br \/>\n(29076)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(606)<\/td>\n<td style=\"width: 20%; text-align: center;\">761<br \/>\n(801)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">612<br \/>\n(622)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24616<br \/>\n(29616)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(618)<\/td>\n<td style=\"width: 20%; text-align: center;\">769<br \/>\n(809)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">622<br \/>\n(632)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25156<br \/>\n(30156)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(630)<\/td>\n<td style=\"width: 20%; text-align: center;\">777<br \/>\n(817)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">632<br \/>\n(642)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25826<br \/>\n(30826)<\/td>\n<td style=\"width: 20%; text-align: center;\">644<br \/>\n(644)<\/td>\n<td style=\"width: 20%; text-align: center;\">787<br \/>\n(827)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">644<br \/>\n(654)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26776<br \/>\n(31776)<\/td>\n<td style=\"width: 20%; text-align: center;\">666<br \/>\n(666)<\/td>\n<td style=\"width: 20%; text-align: center;\">801<br \/>\n(841)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">662<br \/>\n(672)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24586<br \/>\n(29586)<\/td>\n<td style=\"width: 20%; text-align: center;\">615<br \/>\n(615)<\/td>\n<td style=\"width: 20%; text-align: center;\">770<br \/>\n(810)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">621<br \/>\n(631)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25126<br \/>\n(30126)<\/td>\n<td style=\"width: 20%; text-align: center;\">627<br \/>\n(627)<\/td>\n<td style=\"width: 20%; text-align: center;\">778<br \/>\n(818)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">631<br \/>\n(641)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25666<br \/>\n(30666)<\/td>\n<td style=\"width: 20%; text-align: center;\">639<br \/>\n(639)<\/td>\n<td style=\"width: 20%; text-align: center;\">786<br \/>\n(826)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">641<br \/>\n(651)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26336<br \/>\n(31336)<\/td>\n<td style=\"width: 20%; text-align: center;\">653<br \/>\n(653)<\/td>\n<td style=\"width: 20%; text-align: center;\">796<br \/>\n(836)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">653<br \/>\n(663)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27286<br \/>\n(32286)<\/td>\n<td style=\"width: 20%; text-align: center;\">675<br \/>\n(675)<\/td>\n<td style=\"width: 20%; text-align: center;\">810<br \/>\n(850)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">671<br \/>\n(681)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24766<br \/>\n(29766)<\/td>\n<td style=\"width: 20%; text-align: center;\">617<br \/>\n(617)<\/td>\n<td style=\"width: 20%; text-align: center;\">772<br \/>\n(812)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">622<br \/>\n(632)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25306<br \/>\n(30306)<\/td>\n<td style=\"width: 20%; text-align: center;\">629<br \/>\n(629)<\/td>\n<td style=\"width: 20%; text-align: center;\">780<br \/>\n(820)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">632<br \/>\n(642)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25846<br \/>\n(30846)<\/td>\n<td style=\"width: 20%; text-align: center;\">641<br \/>\n(641)<\/td>\n<td style=\"width: 20%; text-align: center;\">788<br \/>\n(828)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">642<br \/>\n(652)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26516<br \/>\n(31516)<\/td>\n<td style=\"width: 20%; text-align: center;\">655<br \/>\n(655)<\/td>\n<td style=\"width: 20%; text-align: center;\">798<br \/>\n(838)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">654<br \/>\n(664)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27466<br \/>\n(32466)<\/td>\n<td style=\"width: 20%; text-align: center;\">677<br \/>\n(677)<\/td>\n<td style=\"width: 20%; text-align: center;\">812<br \/>\n(852)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">672<br \/>\n(682)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24961<br \/>\n(29961)<\/td>\n<td style=\"width: 20%; text-align: center;\">619<br \/>\n(619)<\/td>\n<td style=\"width: 20%; text-align: center;\">774<br \/>\n(814)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">624<br \/>\n(634)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25501<br \/>\n(30501)<\/td>\n<td style=\"width: 20%; text-align: center;\">631<br \/>\n(631)<\/td>\n<td style=\"width: 20%; text-align: center;\">782<br \/>\n(822)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">634<br \/>\n(644)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26041<br \/>\n(31041)<\/td>\n<td style=\"width: 20%; text-align: center;\">643<br \/>\n(643)<\/td>\n<td style=\"width: 20%; text-align: center;\">790<br \/>\n(830)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">644<br \/>\n(654)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26711<br \/>\n(31711)<\/td>\n<td style=\"width: 20%; text-align: center;\">657<br \/>\n(657)<\/td>\n<td style=\"width: 20%; text-align: center;\">800<br \/>\n(840)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">656<br \/>\n(666)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27661<br \/>\n(32661)<\/td>\n<td style=\"width: 20%; text-align: center;\">679<br \/>\n(679)<\/td>\n<td style=\"width: 20%; text-align: center;\">814<br \/>\n(854)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">674<br \/>\n(684)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25166<br \/>\n(30166)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(622)<\/td>\n<td style=\"width: 20%; text-align: center;\">777<br \/>\n(817)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">626<br \/>\n(636)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25706<br \/>\n(30706)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(634)<\/td>\n<td style=\"width: 20%; text-align: center;\">785<br \/>\n(825)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">636<br \/>\n(646)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26246<br \/>\n(31246)<\/td>\n<td style=\"width: 20%; text-align: center;\">646<br \/>\n(646)<\/td>\n<td style=\"width: 20%; text-align: center;\">793<br \/>\n(833)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">646<br \/>\n(656)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26916<br \/>\n(31916)<\/td>\n<td style=\"width: 20%; text-align: center;\">660<br \/>\n(660)<\/td>\n<td style=\"width: 20%; text-align: center;\">803<br \/>\n(843)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">658<br \/>\n(668)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27866<br \/>\n(32866)<\/td>\n<td style=\"width: 20%; text-align: center;\">682<br \/>\n(682)<\/td>\n<td style=\"width: 20%; text-align: center;\">817<br \/>\n(857)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">676<br \/>\n(686)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25381<br \/>\n(30381)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(624)<\/td>\n<td style=\"width: 20%; text-align: center;\">779<br \/>\n(819)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">628<br \/>\n(638)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25921<br \/>\n(30921)<\/td>\n<td style=\"width: 20%; text-align: center;\">636<br \/>\n(636)<\/td>\n<td style=\"width: 20%; text-align: center;\">787<br \/>\n(827)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">638<br \/>\n(648)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26461<br \/>\n(31461)<\/td>\n<td style=\"width: 20%; text-align: center;\">648<br \/>\n(648)<\/td>\n<td style=\"width: 20%; text-align: center;\">795<br \/>\n(835)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">648<br \/>\n(658)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27131<br \/>\n(32131)<\/td>\n<td style=\"width: 20%; text-align: center;\">662<br \/>\n(662)<\/td>\n<td style=\"width: 20%; text-align: center;\">805<br \/>\n(845)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">660<br \/>\n(670)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28081<br \/>\n(33081)<\/td>\n<td style=\"width: 20%; text-align: center;\">684<br \/>\n(684)<\/td>\n<td style=\"width: 20%; text-align: center;\">819<br \/>\n(859)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">678<br \/>\n(688)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25611<br \/>\n(30611)<\/td>\n<td style=\"width: 20%; text-align: center;\">627<br \/>\n(627)<\/td>\n<td style=\"width: 20%; text-align: center;\">782<br \/>\n(822)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">630<br \/>\n(640)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26151<br \/>\n(31151)<\/td>\n<td style=\"width: 20%; text-align: center;\">639<br \/>\n(639)<\/td>\n<td style=\"width: 20%; text-align: center;\">790<br \/>\n(830)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">640<br \/>\n(650)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26691<br \/>\n(31691)<\/td>\n<td style=\"width: 20%; text-align: center;\">651<br \/>\n(651)<\/td>\n<td style=\"width: 20%; text-align: center;\">798<br \/>\n(838)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">650<br \/>\n(660)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27361<br \/>\n(32361)<\/td>\n<td style=\"width: 20%; text-align: center;\">665<br \/>\n(665)<\/td>\n<td style=\"width: 20%; text-align: center;\">808<br \/>\n(848)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">662<br \/>\n(672)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28311<br \/>\n(33311)<\/td>\n<td style=\"width: 20%; text-align: center;\">687<br \/>\n(687)<\/td>\n<td style=\"width: 20%; text-align: center;\">822<br \/>\n(862)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">680<br \/>\n(690)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25851<br \/>\n(30851)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(630)<\/td>\n<td style=\"width: 20%; text-align: center;\">785<br \/>\n(825)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">632<br \/>\n(642)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26391<br \/>\n(31391)<\/td>\n<td style=\"width: 20%; text-align: center;\">642<br \/>\n(642)<\/td>\n<td style=\"width: 20%; text-align: center;\">793<br \/>\n(833)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">642<br \/>\n(652)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26931<br \/>\n(31931)<\/td>\n<td style=\"width: 20%; text-align: center;\">654<br \/>\n(654)<\/td>\n<td style=\"width: 20%; text-align: center;\">801<br \/>\n(841)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">652<br \/>\n(662)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27601<br \/>\n(32601)<\/td>\n<td style=\"width: 20%; text-align: center;\">668<br \/>\n(668)<\/td>\n<td style=\"width: 20%; text-align: center;\">811<br \/>\n(851)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">664<br \/>\n(674)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28551<br \/>\n(33551)<\/td>\n<td style=\"width: 20%; text-align: center;\">690<br \/>\n(690)<\/td>\n<td style=\"width: 20%; text-align: center;\">825<br \/>\n(865)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">682<br \/>\n(692)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">26111<br \/>\n(31111)<\/td>\n<td style=\"width: 20%; text-align: center;\">633<br \/>\n(633)<\/td>\n<td style=\"width: 20%; text-align: center;\">788<br \/>\n(828)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">635<br \/>\n(645)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26651<br \/>\n(31651)<\/td>\n<td style=\"width: 20%; text-align: center;\">645<br \/>\n(645)<\/td>\n<td style=\"width: 20%; text-align: center;\">796<br \/>\n(836)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">645<br \/>\n(655)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">27191<br \/>\n(32191)<\/td>\n<td style=\"width: 20%; text-align: center;\">657<br \/>\n(657)<\/td>\n<td style=\"width: 20%; text-align: center;\">804<br \/>\n(844)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">655<br \/>\n(665)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27861<br \/>\n(32861)<\/td>\n<td style=\"width: 20%; text-align: center;\">671<br \/>\n(671)<\/td>\n<td style=\"width: 20%; text-align: center;\">814<br \/>\n(854)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">667<br \/>\n(677)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28811<br \/>\n(33811)<\/td>\n<td style=\"width: 20%; text-align: center;\">693<br \/>\n(693)<\/td>\n<td style=\"width: 20%; text-align: center;\">828<br \/>\n(868)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">685<br \/>\n(695)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">26396<br \/>\n(31396)<\/td>\n<td style=\"width: 20%; text-align: center;\">637<br \/>\n(637)<\/td>\n<td style=\"width: 20%; text-align: center;\">792<br \/>\n(832)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">638<br \/>\n(648)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26936<br \/>\n(31936)<\/td>\n<td style=\"width: 20%; text-align: center;\">649<br \/>\n(649)<\/td>\n<td style=\"width: 20%; text-align: center;\">800<br \/>\n(840)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">648<br \/>\n(658)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">27476<br \/>\n(32476)<\/td>\n<td style=\"width: 20%; text-align: center;\">661<br \/>\n(661)<\/td>\n<td style=\"width: 20%; text-align: center;\">808<br \/>\n(848)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">658<br \/>\n(668)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">28146<br \/>\n(33146)<\/td>\n<td style=\"width: 20%; text-align: center;\">675<br \/>\n(675)<\/td>\n<td style=\"width: 20%; text-align: center;\">818<br \/>\n(858)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">670<br \/>\n(680)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">29096<br \/>\n(34096)<\/td>\n<td style=\"width: 20%; text-align: center;\">697<br \/>\n(697)<\/td>\n<td style=\"width: 20%; text-align: center;\">832<br \/>\n(872)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">688<br \/>\n(698)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<div id=\"FD2\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD2-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-2\"><li class=\"active\"><a class=\"\" href=\"#pane-2-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-2-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23876<br \/>\n(26876)<\/td>\n<td style=\"width: 20%; text-align: center;\">716<br \/>\n(776)<\/td>\n<td style=\"width: 20%; text-align: center;\">681<br \/>\n(691)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">572<br \/>\n(572)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24416<br \/>\n(27416)<\/td>\n<td style=\"width: 20%; text-align: center;\">728<br \/>\n(788)<\/td>\n<td style=\"width: 20%; text-align: center;\">689<br \/>\n(699)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">582<br \/>\n(582)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24956<br \/>\n(27956)<\/td>\n<td style=\"width: 20%; text-align: center;\">740<br \/>\n(800)<\/td>\n<td style=\"width: 20%; text-align: center;\">697<br \/>\n(707)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">592<br \/>\n(592)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25626<br \/>\n(28626)<\/td>\n<td style=\"width: 20%; text-align: center;\">754<br \/>\n(814)<\/td>\n<td style=\"width: 20%; text-align: center;\">707<br \/>\n(717)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">604<br \/>\n(604)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">26576<br \/>\n(29576)<\/td>\n<td style=\"width: 20%; text-align: center;\">776<br \/>\n(836)<\/td>\n<td style=\"width: 20%; text-align: center;\">721<br \/>\n(731)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">622<br \/>\n(622)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24386<br \/>\n(27386)<\/td>\n<td style=\"width: 20%; text-align: center;\">725<br \/>\n(785)<\/td>\n<td style=\"width: 20%; text-align: center;\">690<br \/>\n(700)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">581<br \/>\n(581)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">24926<br \/>\n(27926)<\/td>\n<td style=\"width: 20%; text-align: center;\">737<br \/>\n(797)<\/td>\n<td style=\"width: 20%; text-align: center;\">698<br \/>\n(708)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">591<br \/>\n(591)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25466<br \/>\n(28466)<\/td>\n<td style=\"width: 20%; text-align: center;\">749<br \/>\n(809)<\/td>\n<td style=\"width: 20%; text-align: center;\">706<br \/>\n(716)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">601<br \/>\n(601)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26136<br \/>\n(29136)<\/td>\n<td style=\"width: 20%; text-align: center;\">763<br \/>\n(823)<\/td>\n<td style=\"width: 20%; text-align: center;\">716<br \/>\n(726)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">613<br \/>\n(613)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27086<br \/>\n(30086)<\/td>\n<td style=\"width: 20%; text-align: center;\">785<br \/>\n(845)<\/td>\n<td style=\"width: 20%; text-align: center;\">730<br \/>\n(740)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">631<br \/>\n(631)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24566<br \/>\n(27566)<\/td>\n<td style=\"width: 20%; text-align: center;\">727<br \/>\n(787)<\/td>\n<td style=\"width: 20%; text-align: center;\">692<br \/>\n(702)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">582<br \/>\n(582)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25106<br \/>\n(28106)<\/td>\n<td style=\"width: 20%; text-align: center;\">739<br \/>\n(799)<\/td>\n<td style=\"width: 20%; text-align: center;\">700<br \/>\n(710)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">592<br \/>\n(592)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25646<br \/>\n(28646)<\/td>\n<td style=\"width: 20%; text-align: center;\">751<br \/>\n(811)<\/td>\n<td style=\"width: 20%; text-align: center;\">708<br \/>\n(718)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">602<br \/>\n(602)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26316<br \/>\n(29316)<\/td>\n<td style=\"width: 20%; text-align: center;\">765<br \/>\n(825)<\/td>\n<td style=\"width: 20%; text-align: center;\">718<br \/>\n(728)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">614<br \/>\n(614)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27266<br \/>\n(30266)<\/td>\n<td style=\"width: 20%; text-align: center;\">787<br \/>\n(847)<\/td>\n<td style=\"width: 20%; text-align: center;\">732<br \/>\n(742)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">632<br \/>\n(632)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24761<br \/>\n(27761)<\/td>\n<td style=\"width: 20%; text-align: center;\">729<br \/>\n(789)<\/td>\n<td style=\"width: 20%; text-align: center;\">694<br \/>\n(704)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">584<br \/>\n(584)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25301<br \/>\n(28301)<\/td>\n<td style=\"width: 20%; text-align: center;\">741<br \/>\n(801)<\/td>\n<td style=\"width: 20%; text-align: center;\">702<br \/>\n(712)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">594<br \/>\n(594)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">25841<br \/>\n(28841)<\/td>\n<td style=\"width: 20%; text-align: center;\">753<br \/>\n(813)<\/td>\n<td style=\"width: 20%; text-align: center;\">710<br \/>\n(720)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">604<br \/>\n(604)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26511<br \/>\n(29511)<\/td>\n<td style=\"width: 20%; text-align: center;\">767<br \/>\n(827)<\/td>\n<td style=\"width: 20%; text-align: center;\">720<br \/>\n(730)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">616<br \/>\n(616)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27461<br \/>\n(30461)<\/td>\n<td style=\"width: 20%; text-align: center;\">789<br \/>\n(849)<\/td>\n<td style=\"width: 20%; text-align: center;\">734<br \/>\n(744)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">634<br \/>\n(634)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">24966<br \/>\n(27966)<\/td>\n<td style=\"width: 20%; text-align: center;\">732<br \/>\n(792)<\/td>\n<td style=\"width: 20%; text-align: center;\">697<br \/>\n(707)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">586<br \/>\n(586)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25506<br \/>\n(28506)<\/td>\n<td style=\"width: 20%; text-align: center;\">744<br \/>\n(804)<\/td>\n<td style=\"width: 20%; text-align: center;\">705<br \/>\n(715)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">596<br \/>\n(596)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26046<br \/>\n(29046)<\/td>\n<td style=\"width: 20%; text-align: center;\">756<br \/>\n(816)<\/td>\n<td style=\"width: 20%; text-align: center;\">713<br \/>\n(723)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">606<br \/>\n(606)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26716<br \/>\n(29716)<\/td>\n<td style=\"width: 20%; text-align: center;\">770<br \/>\n(830)<\/td>\n<td style=\"width: 20%; text-align: center;\">723<br \/>\n(733)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">618<br \/>\n(618)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27666<br \/>\n(30666)<\/td>\n<td style=\"width: 20%; text-align: center;\">792<br \/>\n(852)<\/td>\n<td style=\"width: 20%; text-align: center;\">737<br \/>\n(747)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">636<br \/>\n(636)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25181<br \/>\n(28181)<\/td>\n<td style=\"width: 20%; text-align: center;\">734<br \/>\n(794)<\/td>\n<td style=\"width: 20%; text-align: center;\">699<br \/>\n(709)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">588<br \/>\n(588)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25721<br \/>\n(28721)<\/td>\n<td style=\"width: 20%; text-align: center;\">746<br \/>\n(806)<\/td>\n<td style=\"width: 20%; text-align: center;\">707<br \/>\n(717)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">598<br \/>\n(598)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26261<br \/>\n(29261)<\/td>\n<td style=\"width: 20%; text-align: center;\">758<br \/>\n(818)<\/td>\n<td style=\"width: 20%; text-align: center;\">715<br \/>\n(725)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">608<br \/>\n(608)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">26931<br \/>\n(29931)<\/td>\n<td style=\"width: 20%; text-align: center;\">772<br \/>\n(832)<\/td>\n<td style=\"width: 20%; text-align: center;\">725<br \/>\n(735)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">620<br \/>\n(620)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">27881<br \/>\n(30881)<\/td>\n<td style=\"width: 20%; text-align: center;\">794<br \/>\n(854)<\/td>\n<td style=\"width: 20%; text-align: center;\">739<br \/>\n(749)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">638<br \/>\n(638)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25411<br \/>\n(28411)<\/td>\n<td style=\"width: 20%; text-align: center;\">737<br \/>\n(797)<\/td>\n<td style=\"width: 20%; text-align: center;\">702<br \/>\n(712)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">590<br \/>\n(590)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">25951<br \/>\n(28951)<\/td>\n<td style=\"width: 20%; text-align: center;\">749<br \/>\n(809)<\/td>\n<td style=\"width: 20%; text-align: center;\">710<br \/>\n(720)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">600<br \/>\n(600)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26491<br \/>\n(29491)<\/td>\n<td style=\"width: 20%; text-align: center;\">761<br \/>\n(821)<\/td>\n<td style=\"width: 20%; text-align: center;\">718<br \/>\n(728)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">610<br \/>\n(610)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27161<br \/>\n(30161)<\/td>\n<td style=\"width: 20%; text-align: center;\">775<br \/>\n(835)<\/td>\n<td style=\"width: 20%; text-align: center;\">728<br \/>\n(738)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">622<br \/>\n(622)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28111<br \/>\n(31111)<\/td>\n<td style=\"width: 20%; text-align: center;\">797<br \/>\n(857)<\/td>\n<td style=\"width: 20%; text-align: center;\">742<br \/>\n(752)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">640<br \/>\n(640)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25651<br \/>\n(28651)<\/td>\n<td style=\"width: 20%; text-align: center;\">740<br \/>\n(800)<\/td>\n<td style=\"width: 20%; text-align: center;\">705<br \/>\n(715)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">592<br \/>\n(592)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26191<br \/>\n(29191)<\/td>\n<td style=\"width: 20%; text-align: center;\">752<br \/>\n(812)<\/td>\n<td style=\"width: 20%; text-align: center;\">713<br \/>\n(723)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">602<br \/>\n(602)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26731<br \/>\n(29731)<\/td>\n<td style=\"width: 20%; text-align: center;\">764<br \/>\n(824)<\/td>\n<td style=\"width: 20%; text-align: center;\">721<br \/>\n(731)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">612<br \/>\n(612)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27401<br \/>\n(30401)<\/td>\n<td style=\"width: 20%; text-align: center;\">778<br \/>\n(838)<\/td>\n<td style=\"width: 20%; text-align: center;\">731<br \/>\n(741)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">624<br \/>\n(624)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28351<br \/>\n(31351)<\/td>\n<td style=\"width: 20%; text-align: center;\">800<br \/>\n(860)<\/td>\n<td style=\"width: 20%; text-align: center;\">745<br \/>\n(755)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">642<br \/>\n(642)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">25911<br \/>\n(28911)<\/td>\n<td style=\"width: 20%; text-align: center;\">743<br \/>\n(803)<\/td>\n<td style=\"width: 20%; text-align: center;\">708<br \/>\n(718)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">595<br \/>\n(595)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26451<br \/>\n(29451)<\/td>\n<td style=\"width: 20%; text-align: center;\">755<br \/>\n(815)<\/td>\n<td style=\"width: 20%; text-align: center;\">716<br \/>\n(726)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">605<br \/>\n(605)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">26991<br \/>\n(29991)<\/td>\n<td style=\"width: 20%; text-align: center;\">767<br \/>\n(827)<\/td>\n<td style=\"width: 20%; text-align: center;\">724<br \/>\n(734)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">615<br \/>\n(615)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27661<br \/>\n(30661)<\/td>\n<td style=\"width: 20%; text-align: center;\">781<br \/>\n(841)<\/td>\n<td style=\"width: 20%; text-align: center;\">734<br \/>\n(744)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">627<br \/>\n(627)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28611<br \/>\n(31611)<\/td>\n<td style=\"width: 20%; text-align: center;\">803<br \/>\n(863)<\/td>\n<td style=\"width: 20%; text-align: center;\">748<br \/>\n(758)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">645<br \/>\n(645)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">26196<br \/>\n(29196)<\/td>\n<td style=\"width: 20%; text-align: center;\">747<br \/>\n(807)<\/td>\n<td style=\"width: 20%; text-align: center;\">712<br \/>\n(722)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">598<br \/>\n(598)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">26736<br \/>\n(29736)<\/td>\n<td style=\"width: 20%; text-align: center;\">759<br \/>\n(819)<\/td>\n<td style=\"width: 20%; text-align: center;\">720<br \/>\n(730)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">608<br \/>\n(608)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">27276<br \/>\n(30276)<\/td>\n<td style=\"width: 20%; text-align: center;\">771<br \/>\n(831)<\/td>\n<td style=\"width: 20%; text-align: center;\">728<br \/>\n(738)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">618<br \/>\n(618)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">27946<br \/>\n(30946)<\/td>\n<td style=\"width: 20%; text-align: center;\">785<br \/>\n(845)<\/td>\n<td style=\"width: 20%; text-align: center;\">738<br \/>\n(748)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">630<br \/>\n(630)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">28896<br \/>\n(31896)<\/td>\n<td style=\"width: 20%; text-align: center;\">807<br \/>\n(867)<\/td>\n<td style=\"width: 20%; text-align: center;\">752<br \/>\n(762)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">648<br \/>\n(648)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<p><span style=\"color: #ff0000; font-size: 10pt;\">\u2022The number between () indicates the stat value at maximum Type Boost<\/span><\/p>\n<h2 class=\"sexypurple\" style=\"text-align: center;\">Normal Attack<\/h2>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 1: Single Stwike (\u3057\u3093\u3050\u308b\u3059\u3068\u3089\u3044\u304f)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">45 (58)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">None<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 2: Dwouble Stwike (\u3060\u3076\u308b\u3059\u3068\u3089\u3044\u304f)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">70 (91)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">3<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">None<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 3: Twiple Stwike (\u3068\u308a\u3077\u308b\u3059\u3068\u3089\u3044\u304f)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">95 (123)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">5<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">Reduce Target attack by 10% (2 turns)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"sexyblue\" style=\"text-align: center;\">\nSkills<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-3\"><li class=\"active\"><a class=\"\" href=\"#pane-3-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-3-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-3-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-3-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Little Bird Manage (\u30ea\u30c8\u30eb\u30d0\u30fc\u30c9\u30de\u30cd\u30fc\u30b8\u30e5)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Allies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">3<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td style=\"vertical-align: middle;\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Little Bird&#039;s Blessing\" data-contentwrapper=\"osc_popover_1\"> Little Bird&#039;s Blessing <\/button><div id=\"osc_popover_1\" style=\"display:none;\">Survive with 1HP instead of dying. Afterwards heal for 15% of your HP.<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    to All Allies (2 turns)<\/li>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Reduce Element Use\" data-contentwrapper=\"osc_popover_2\"> Reduce Element Use <\/button><div id=\"osc_popover_2\" style=\"display:none;\">Reduces the amount of Element used<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 1 to All Allies (3 turns)<\/li>\n<\/ol>\n<p>Cool-down: 16 (12) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Cabriolet Bloom (\u30ab\u30d6\u30ea\u30aa\u30eb\u30d6\u30eb\u30fc\u30e0)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">80 (160)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">6<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>30% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Confusion\" data-contentwrapper=\"osc_popover_3\"> Confusion <\/button><div id=\"osc_popover_3\" style=\"display:none;\"> Causes Target to use random attacks<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>If own Element Value is 7 or higher, reduce Target&#8217;s defense by 20% (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-3-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Little Bird Manage [Defense Type] (\u30ea\u30c8\u30eb\u30d0\u30fc\u30c9\u30de\u30cd\u30fc\u30b8\u30e5[\u9632])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Allies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">3<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"vertical-align: middle; width: 75%;\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Little Bird&#039;s Blessing\" data-contentwrapper=\"osc_popover_4\"> Little Bird&#039;s Blessing <\/button><div id=\"osc_popover_4\" style=\"display:none;\">Survive with 1HP instead of dying. Afterwards heal for 15% of your HP.<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    to All Allies (2 turns)<\/li>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Reduce Element Use\" data-contentwrapper=\"osc_popover_5\"> Reduce Element Use <\/button><div id=\"osc_popover_5\" style=\"display:none;\">Reduces the amount of Element used<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 1 to All Allies (3 turns)<\/li>\n<li>Increase defense of All Allies by 10% (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 16 (12) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Cabriolet Bloom [Defense Type] (\u30ab\u30d6\u30ea\u30aa\u30eb\u30d6\u30eb\u30fc\u30e0[\u9632])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">80 (160)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">5<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>10% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Confusion\" data-contentwrapper=\"osc_popover_6\"> Confusion <\/button><div id=\"osc_popover_6\" style=\"display:none;\"> Causes Target to use random attacks<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>If own Element Value is 7 or higher, reduce Target&#8217;s attack by 20% (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-3-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Little Bird Manage [Attack Type] (\u30ea\u30c8\u30eb\u30d0\u30fc\u30c9\u30de\u30cd\u30fc\u30b8\u30e5[\u653b])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Allies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">2<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"vertical-align: middle; width: 75%;\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Little Bird&#039;s Blessing\" data-contentwrapper=\"osc_popover_7\"> Little Bird&#039;s Blessing <\/button><div id=\"osc_popover_7\" style=\"display:none;\">Survive with 1HP instead of dying. Afterwards heal for 15% of your HP.<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    to All Allies (2 turns)<\/li>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Reduce Element Use\" data-contentwrapper=\"osc_popover_8\"> Reduce Element Use <\/button><div id=\"osc_popover_8\" style=\"display:none;\">Reduces the amount of Element used<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 1 to All Allies (3 turns)<\/li>\n<\/ol>\n<p>Cool-down: 16 (12) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Cabriolet Bloom [Attack Type] (\u30ab\u30d6\u30ea\u30aa\u30eb\u30d6\u30eb\u30fc\u30e0[\u653b])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">100 (180)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">5<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>30% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Confusion\" data-contentwrapper=\"osc_popover_9\"> Confusion <\/button><div id=\"osc_popover_9\" style=\"display:none;\"> Causes Target to use random attacks<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<h2 class=\"sexyred\" style=\"text-align: center;\">\nElemental Blast<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-4\"><li class=\"active\"><a class=\"\" href=\"#pane-4-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-4-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-4-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-4-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Little Phoenix (\u30ea\u30c8\u30eb\u30d5\u30a7\u30cb\u30c3\u30af\u30b9)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">260 (360)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">6<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">6<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Reduction\" data-contentwrapper=\"osc_popover_10\"> Damage Reduction <\/button><div id=\"osc_popover_10\" style=\"display:none;\">Reduces damage taken<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 15% to All Allies (2 turns)<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\">\n<tbody>\n<tr>\n<th colspan=\"4\">Stage 2: True Little Phoenix (\u771f\u30fb\u30ea\u30c8\u30eb\u30d5\u30a7\u30cb\u30c3\u30af\u30b9(2\u6bb5\u968e\u76ee))<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">350 (510)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">10<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">10<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Reduction\" data-contentwrapper=\"osc_popover_11\"> Damage Reduction <\/button><div id=\"osc_popover_11\" style=\"display:none;\">Reduces damage taken<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 20% to All Allies (2 turns)<\/li>\n<li>This attack always lands a Critical Hit<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-4-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Little Phoenix [Defense Type] (\u30ea\u30c8\u30eb\u30d5\u30a7\u30cb\u30c3\u30af\u30b9[\u9632])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">260 (360)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">6<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">6<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Reduction\" data-contentwrapper=\"osc_popover_12\"> Damage Reduction <\/button><div id=\"osc_popover_12\" style=\"display:none;\">Reduces damage taken<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 15% to All Allies (2 turns)<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Stage 2: True Little Phoenix [Defense Type] (\u771f\u30fb\u30ea\u30c8\u30eb\u30d5\u30a7\u30cb\u30c3\u30af\u30b9[\u9632](2\u6bb5\u968e\u76ee))<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">320 (480)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">10<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">10<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Reduction\" data-contentwrapper=\"osc_popover_13\"> Damage Reduction <\/button><div id=\"osc_popover_13\" style=\"display:none;\">Reduces damage taken<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 20% to All Allies (2 turns)<\/li>\n<li>Applies<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Guts\" data-contentwrapper=\"osc_popover_14\"> Guts <\/button><div id=\"osc_popover_14\" style=\"display:none;\">Survive with 1HP instead of dying <\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n     to All Allies (2 turns)<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-4-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Little Phoenix [Attack Type] (\u30ea\u30c8\u30eb\u30d5\u30a7\u30cb\u30c3\u30af\u30b9[\u653b])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">260 (360)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">6<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">6<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Reduction\" data-contentwrapper=\"osc_popover_15\"> Damage Reduction <\/button><div id=\"osc_popover_15\" style=\"display:none;\">Reduces damage taken<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 15% to All Allies (2 turns)<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Stage 2: True Little Phoenix [Attack Type] (\u771f\u30fb\u30ea\u30c8\u30eb\u30d5\u30a7\u30cb\u30c3\u30af\u30b9[\u653b](2\u6bb5\u968e\u76ee))<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">390 (550)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">10<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">10<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Reduction\" data-contentwrapper=\"osc_popover_16\"> Damage Reduction <\/button><div id=\"osc_popover_16\" style=\"display:none;\">Reduces damage taken<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 20% to All Allies (2 turns)<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&lt; Back to Characters &nbsp; Giselle [Memories] (Law) Defense Type Giselle [Memories] Weak Hit Type Giselle [Memories] (Chaos) Attack Type Rarity Faction Chaos Class Striker Element Earth Idola Andromeda G Type Fates Law Chaos Date 2021\/04\/27 Race Human Character Stats Default Law Chaos \u2022The number between () indicates the stat value at maximum Type Boost [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":567,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-8151","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PatEj8-27t","_links":{"self":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/8151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/comments?post=8151"}],"version-history":[{"count":4,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/8151\/revisions"}],"predecessor-version":[{"id":8619,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/8151\/revisions\/8619"}],"up":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/567"}],"wp:attachment":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/media?parent=8151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}