{"id":7926,"date":"2021-03-22T09:53:50","date_gmt":"2021-03-22T13:53:50","guid":{"rendered":"https:\/\/bumped.org\/idola\/?page_id=7926"},"modified":"2021-10-20T16:55:24","modified_gmt":"2021-10-20T20:55:24","slug":"character-kaempfer-exiled-strategist","status":"publish","type":"page","link":"https:\/\/bumped.org\/idola\/idola-character-database\/character-kaempfer-exiled-strategist\/","title":{"rendered":"Character: Kaempfer [Exiled Strategist]"},"content":{"rendered":"<p><a href=\"https:\/\/bumped.org\/idola\/idola-character-database\/\">&lt; Back to Characters<\/a><\/p>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-law.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7928\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-law.png?resize=440%2C440&#038;ssl=1\" alt=\"\" width=\"440\" height=\"440\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-law.png?w=440&amp;ssl=1 440w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-law.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-law.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-law.png?resize=60%2C60&amp;ssl=1 60w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/td>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7930\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist.png?resize=440%2C440&#038;ssl=1\" alt=\"\" width=\"440\" height=\"440\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist.png?w=440&amp;ssl=1 440w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist.png?resize=60%2C60&amp;ssl=1 60w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/td>\n<td style=\"width: 33.3333%;\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-chaos.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7927\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-chaos.png?resize=440%2C440&#038;ssl=1\" alt=\"\" width=\"440\" height=\"440\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-chaos.png?w=440&amp;ssl=1 440w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-chaos.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-chaos.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2021\/03\/character-kaempfer-exiled-strategist-chaos.png?resize=60%2C60&amp;ssl=1 60w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 33.3333%; text-align: center;\">\n<p>Kaempfer [Exiled Strategist] (Law)<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-weak-hit-damage.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5886\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-weak-hit-damage.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Weak Hit Type<\/p>\n<\/th>\n<th style=\"width: 33.3333%; text-align: center;\">Kaempfer [Exiled Strategist]<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/type-critical-hit-rate.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-5884 alignnone\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/type-critical-hit-rate.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Critical Hit Type<\/th>\n<th style=\"width: 33.3333%; text-align: center;\">Kaempfer [Exiled Strategist] (Chaos)<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/type-status-effect-resistance.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5885\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/type-status-effect-resistance.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Status Resist Type<\/th>\n<\/tr>\n<\/tbody>\n<\/table>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 100%; border-color: #757575;\" border=\"1\" width=\"100%\">\n<thead>\n<tr>\n<td style=\"background-color: #e3e3e3; width: 20%; border-color: grey; text-align: center; vertical-align: middle;\" width=\"20%\">Rarity<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\" width=\"30%\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; width: 20%; text-align: center; vertical-align: middle;\" width=\"20%\">Faction<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\" width=\"30%\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1280\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Chaos-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Chaos<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"border-color: #757575;\">\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Class<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">Wizard<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Element<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1004\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/element-icon-water-e1543528071903.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Water<\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Idola<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1079\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/idola-icon-7-e1543537574755.png?resize=17%2C22&#038;ssl=1\" alt=\"\" width=\"17\" height=\"22\" \/> Andromeda<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Fates<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1281\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Law-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Law<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1280\" style=\"vertical-align: middle;\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Chaos-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Chaos<\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Date<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">2021\/03\/22<\/td>\n<td style=\"border-color: grey; background-color: #e3e3e3; text-align: center; vertical-align: middle;\">Race<\/td>\n<td style=\"border-color: grey; vertical-align: middle;\">Elf<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"sexyblue\" style=\"text-align: center;\">Character Stats<\/h2>\n<ul id=\"DBLimits\" class=\"nav nav-tabs\" role=\"tablist\">\n<li class=\"nav-item\"><a id=\"limi0-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD0\" data-toggle=\"tab\">Default<\/a><\/li>\n<li class=\"nav-item\"><a id=\"limi1-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD1\" data-toggle=\"tab\">Law<\/a><\/li>\n<li class=\"nav-item\"><a id=\"limi2-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD2\" data-toggle=\"tab\">Chaos<\/a><\/li>\n<\/ul>\n<div id=\"DBStats\" class=\"tab-content small\">\n<div id=\"FD0\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD0-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-0\"><li class=\"active\"><a class=\"\" href=\"#pane-0-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-0-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21056<br \/>\n(23556)<\/td>\n<td style=\"width: 20%; text-align: center;\">562<br \/>\n(562)<\/td>\n<td style=\"width: 20%; text-align: center;\">574<br \/>\n(584)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">586<br \/>\n(616)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">21596<br \/>\n(24096)<\/td>\n<td style=\"width: 20%; text-align: center;\">574<br \/>\n(574)<\/td>\n<td style=\"width: 20%; text-align: center;\">582<br \/>\n(592)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">596<br \/>\n(626)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22136<br \/>\n(24636)<\/td>\n<td style=\"width: 20%; text-align: center;\">586<br \/>\n(586)<\/td>\n<td style=\"width: 20%; text-align: center;\">590<br \/>\n(600)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">606<br \/>\n(636)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">22806<br \/>\n(25306)<\/td>\n<td style=\"width: 20%; text-align: center;\">600<br \/>\n(600)<\/td>\n<td style=\"width: 20%; text-align: center;\">600<br \/>\n(610)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">618<br \/>\n(648)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">23756<br \/>\n(26256)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(622)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">636<br \/>\n(666)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21546<br \/>\n(24046)<\/td>\n<td style=\"width: 20%; text-align: center;\">572<br \/>\n(572)<\/td>\n<td style=\"width: 20%; text-align: center;\">582<br \/>\n(592)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">595<br \/>\n(625)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22086<br \/>\n(24586)<\/td>\n<td style=\"width: 20%; text-align: center;\">584<br \/>\n(584)<\/td>\n<td style=\"width: 20%; text-align: center;\">590<br \/>\n(600)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">605<br \/>\n(635)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22626<br \/>\n(25126)<\/td>\n<td style=\"width: 20%; text-align: center;\">596<br \/>\n(596)<\/td>\n<td style=\"width: 20%; text-align: center;\">598<br \/>\n(608)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">615<br \/>\n(645)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23296<br \/>\n(25796)<\/td>\n<td style=\"width: 20%; text-align: center;\">610<br \/>\n(610)<\/td>\n<td style=\"width: 20%; text-align: center;\">608<br \/>\n(618)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">627<br \/>\n(657)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24246<br \/>\n(26746)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(632)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(632)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">645<br \/>\n(675)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21696<br \/>\n(24196)<\/td>\n<td style=\"width: 20%; text-align: center;\">574<br \/>\n(574)<\/td>\n<td style=\"width: 20%; text-align: center;\">583<br \/>\n(593)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">596<br \/>\n(626)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22236<br \/>\n(24736)<\/td>\n<td style=\"width: 20%; text-align: center;\">586<br \/>\n(586)<\/td>\n<td style=\"width: 20%; text-align: center;\">591<br \/>\n(601)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">606<br \/>\n(636)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22776<br \/>\n(25276)<\/td>\n<td style=\"width: 20%; text-align: center;\">598<br \/>\n(598)<\/td>\n<td style=\"width: 20%; text-align: center;\">599<br \/>\n(609)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">616<br \/>\n(646)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23446<br \/>\n(25946)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(612)<\/td>\n<td style=\"width: 20%; text-align: center;\">609<br \/>\n(619)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">628<br \/>\n(658)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24396<br \/>\n(26896)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(634)<\/td>\n<td style=\"width: 20%; text-align: center;\">623<br \/>\n(633)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">646<br \/>\n(676)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21866<br \/>\n(24366)<\/td>\n<td style=\"width: 20%; text-align: center;\">576<br \/>\n(576)<\/td>\n<td style=\"width: 20%; text-align: center;\">584<br \/>\n(594)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">597<br \/>\n(627)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22406<br \/>\n(24906)<\/td>\n<td style=\"width: 20%; text-align: center;\">588<br \/>\n(588)<\/td>\n<td style=\"width: 20%; text-align: center;\">592<br \/>\n(602)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">607<br \/>\n(637)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22946<br \/>\n(25446)<\/td>\n<td style=\"width: 20%; text-align: center;\">600<br \/>\n(600)<\/td>\n<td style=\"width: 20%; text-align: center;\">600<br \/>\n(610)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">617<br \/>\n(647)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23616<br \/>\n(26116)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(614)<\/td>\n<td style=\"width: 20%; text-align: center;\">610<br \/>\n(620)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">629<br \/>\n(659)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24566<br \/>\n(27066)<\/td>\n<td style=\"width: 20%; text-align: center;\">636<br \/>\n(636)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(634)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">647<br \/>\n(677)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22051<br \/>\n(24551)<\/td>\n<td style=\"width: 20%; text-align: center;\">579<br \/>\n(579)<\/td>\n<td style=\"width: 20%; text-align: center;\">585<br \/>\n(595)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">599<br \/>\n(629)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22591<br \/>\n(25091)<\/td>\n<td style=\"width: 20%; text-align: center;\">591<br \/>\n(591)<\/td>\n<td style=\"width: 20%; text-align: center;\">593<br \/>\n(603)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">609<br \/>\n(639)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23131<br \/>\n(25631)<\/td>\n<td style=\"width: 20%; text-align: center;\">603<br \/>\n(603)<\/td>\n<td style=\"width: 20%; text-align: center;\">601<br \/>\n(611)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">619<br \/>\n(649)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23801<br \/>\n(26301)<\/td>\n<td style=\"width: 20%; text-align: center;\">617<br \/>\n(617)<\/td>\n<td style=\"width: 20%; text-align: center;\">611<br \/>\n(621)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">631<br \/>\n(661)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24751<br \/>\n(27251)<\/td>\n<td style=\"width: 20%; text-align: center;\">639<br \/>\n(639)<\/td>\n<td style=\"width: 20%; text-align: center;\">625<br \/>\n(635)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">649<br \/>\n(679)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22256<br \/>\n(24756)<\/td>\n<td style=\"width: 20%; text-align: center;\">582<br \/>\n(582)<\/td>\n<td style=\"width: 20%; text-align: center;\">586<br \/>\n(596)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">601<br \/>\n(631)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22796<br \/>\n(25296)<\/td>\n<td style=\"width: 20%; text-align: center;\">594<br \/>\n(594)<\/td>\n<td style=\"width: 20%; text-align: center;\">594<br \/>\n(604)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">611<br \/>\n(641)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23336<br \/>\n(25836)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(606)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(612)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">621<br \/>\n(651)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24006<br \/>\n(26506)<\/td>\n<td style=\"width: 20%; text-align: center;\">620<br \/>\n(620)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(622)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">633<br \/>\n(663)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24956<br \/>\n(27456)<\/td>\n<td style=\"width: 20%; text-align: center;\">642<br \/>\n(642)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(636)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">651<br \/>\n(681)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22481<br \/>\n(24981)<\/td>\n<td style=\"width: 20%; text-align: center;\">586<br \/>\n(586)<\/td>\n<td style=\"width: 20%; text-align: center;\">588<br \/>\n(598)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">603<br \/>\n(633)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23021<br \/>\n(25521)<\/td>\n<td style=\"width: 20%; text-align: center;\">598<br \/>\n(598)<\/td>\n<td style=\"width: 20%; text-align: center;\">596<br \/>\n(606)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">613<br \/>\n(643)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23561<br \/>\n(26061)<\/td>\n<td style=\"width: 20%; text-align: center;\">610<br \/>\n(610)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(614)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">623<br \/>\n(653)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24231<br \/>\n(26731)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(624)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">635<br \/>\n(665)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25181<br \/>\n(27681)<\/td>\n<td style=\"width: 20%; text-align: center;\">646<br \/>\n(646)<\/td>\n<td style=\"width: 20%; text-align: center;\">628<br \/>\n(638)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">653<br \/>\n(683)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22726<br \/>\n(25226)<\/td>\n<td style=\"width: 20%; text-align: center;\">590<br \/>\n(590)<\/td>\n<td style=\"width: 20%; text-align: center;\">590<br \/>\n(600)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">606<br \/>\n(636)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23266<br \/>\n(25766)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(602)<\/td>\n<td style=\"width: 20%; text-align: center;\">598<br \/>\n(608)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">616<br \/>\n(646)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23806<br \/>\n(26306)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(614)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(616)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">626<br \/>\n(656)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24476<br \/>\n(26976)<\/td>\n<td style=\"width: 20%; text-align: center;\">628<br \/>\n(628)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">638<br \/>\n(668)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25426<br \/>\n(27926)<\/td>\n<td style=\"width: 20%; text-align: center;\">650<br \/>\n(650)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(640)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">656<br \/>\n(686)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22991<br \/>\n(25491)<\/td>\n<td style=\"width: 20%; text-align: center;\">594<br \/>\n(594)<\/td>\n<td style=\"width: 20%; text-align: center;\">593<br \/>\n(603)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">609<br \/>\n(639)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23531<br \/>\n(26031)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(606)<\/td>\n<td style=\"width: 20%; text-align: center;\">601<br \/>\n(611)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">619<br \/>\n(649)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24071<br \/>\n(26571)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(618)<\/td>\n<td style=\"width: 20%; text-align: center;\">609<br \/>\n(619)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">629<br \/>\n(659)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24741<br \/>\n(27241)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(632)<\/td>\n<td style=\"width: 20%; text-align: center;\">619<br \/>\n(629)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">641<br \/>\n(671)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25691<br \/>\n(28191)<\/td>\n<td style=\"width: 20%; text-align: center;\">654<br \/>\n(654)<\/td>\n<td style=\"width: 20%; text-align: center;\">633<br \/>\n(643)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">659<br \/>\n(689)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23276<br \/>\n(25776)<\/td>\n<td style=\"width: 20%; text-align: center;\">599<br \/>\n(599)<\/td>\n<td style=\"width: 20%; text-align: center;\">596<br \/>\n(606)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">613<br \/>\n(643)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23816<br \/>\n(26316)<\/td>\n<td style=\"width: 20%; text-align: center;\">611<br \/>\n(611)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(614)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">623<br \/>\n(653)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24356<br \/>\n(26856)<\/td>\n<td style=\"width: 20%; text-align: center;\">623<br \/>\n(623)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(622)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">633<br \/>\n(663)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25026<br \/>\n(27526)<\/td>\n<td style=\"width: 20%; text-align: center;\">637<br \/>\n(637)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(632)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">645<br \/>\n(675)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25976<br \/>\n(28476)<\/td>\n<td style=\"width: 20%; text-align: center;\">659<br \/>\n(659)<\/td>\n<td style=\"width: 20%; text-align: center;\">636<br \/>\n(646)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">663<br \/>\n(693)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+40 (45)% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<div id=\"FD1\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD1-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-1\"><li class=\"active\"><a class=\"\" href=\"#pane-1-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-1-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21056<br \/>\n(24056)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(622)<\/td>\n<td style=\"width: 20%; text-align: center;\">594<br \/>\n(594)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">526<br \/>\n(546)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">21596<br \/>\n(24596)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(634)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(602)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">536<br \/>\n(556)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22136<br \/>\n(25136)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(646)<\/td>\n<td style=\"width: 20%; text-align: center;\">610<br \/>\n(610)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">546<br \/>\n(566)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">22806<br \/>\n(25806)<\/td>\n<td style=\"width: 20%; text-align: center;\">640<br \/>\n(660)<\/td>\n<td style=\"width: 20%; text-align: center;\">620<br \/>\n(620)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">558<br \/>\n(578)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">23756<br \/>\n(26756)<\/td>\n<td style=\"width: 20%; text-align: center;\">662<br \/>\n(682)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(634)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">576<br \/>\n(596)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21546<br \/>\n(24546)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(632)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(602)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">535<br \/>\n(555)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22086<br \/>\n(25086)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(644)<\/td>\n<td style=\"width: 20%; text-align: center;\">610<br \/>\n(610)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">545<br \/>\n(565)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22626<br \/>\n(25626)<\/td>\n<td style=\"width: 20%; text-align: center;\">636<br \/>\n(656)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(618)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">555<br \/>\n(575)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23296<br \/>\n(26296)<\/td>\n<td style=\"width: 20%; text-align: center;\">650<br \/>\n(670)<\/td>\n<td style=\"width: 20%; text-align: center;\">628<br \/>\n(628)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">567<br \/>\n(587)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24246<br \/>\n(27246)<\/td>\n<td style=\"width: 20%; text-align: center;\">672<br \/>\n(692)<\/td>\n<td style=\"width: 20%; text-align: center;\">642<br \/>\n(642)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">585<br \/>\n(605)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21696<br \/>\n(24696)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(634)<\/td>\n<td style=\"width: 20%; text-align: center;\">603<br \/>\n(603)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">536<br \/>\n(556)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22236<br \/>\n(25236)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(646)<\/td>\n<td style=\"width: 20%; text-align: center;\">611<br \/>\n(611)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">546<br \/>\n(566)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22776<br \/>\n(25776)<\/td>\n<td style=\"width: 20%; text-align: center;\">638<br \/>\n(658)<\/td>\n<td style=\"width: 20%; text-align: center;\">619<br \/>\n(619)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">556<br \/>\n(576)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23446<br \/>\n(26446)<\/td>\n<td style=\"width: 20%; text-align: center;\">652<br \/>\n(672)<\/td>\n<td style=\"width: 20%; text-align: center;\">629<br \/>\n(629)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">568<br \/>\n(588)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24396<br \/>\n(27396)<\/td>\n<td style=\"width: 20%; text-align: center;\">674<br \/>\n(694)<\/td>\n<td style=\"width: 20%; text-align: center;\">643<br \/>\n(643)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">586<br \/>\n(606)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21866<br \/>\n(24866)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(636)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(604)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">537<br \/>\n(557)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22406<br \/>\n(25406)<\/td>\n<td style=\"width: 20%; text-align: center;\">628<br \/>\n(648)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(612)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">547<br \/>\n(567)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22946<br \/>\n(25946)<\/td>\n<td style=\"width: 20%; text-align: center;\">640<br \/>\n(660)<\/td>\n<td style=\"width: 20%; text-align: center;\">620<br \/>\n(620)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">557<br \/>\n(577)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23616<br \/>\n(26616)<\/td>\n<td style=\"width: 20%; text-align: center;\">654<br \/>\n(674)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(630)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">569<br \/>\n(589)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24566<br \/>\n(27566)<\/td>\n<td style=\"width: 20%; text-align: center;\">676<br \/>\n(696)<\/td>\n<td style=\"width: 20%; text-align: center;\">644<br \/>\n(644)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">587<br \/>\n(607)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22051<br \/>\n(25051)<\/td>\n<td style=\"width: 20%; text-align: center;\">619<br \/>\n(639)<\/td>\n<td style=\"width: 20%; text-align: center;\">605<br \/>\n(605)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">539<br \/>\n(559)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22591<br \/>\n(25591)<\/td>\n<td style=\"width: 20%; text-align: center;\">631<br \/>\n(651)<\/td>\n<td style=\"width: 20%; text-align: center;\">613<br \/>\n(613)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">549<br \/>\n(569)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23131<br \/>\n(26131)<\/td>\n<td style=\"width: 20%; text-align: center;\">643<br \/>\n(663)<\/td>\n<td style=\"width: 20%; text-align: center;\">621<br \/>\n(621)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">559<br \/>\n(579)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23801<br \/>\n(26801)<\/td>\n<td style=\"width: 20%; text-align: center;\">657<br \/>\n(677)<\/td>\n<td style=\"width: 20%; text-align: center;\">631<br \/>\n(631)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">571<br \/>\n(591)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24751<br \/>\n(27751)<\/td>\n<td style=\"width: 20%; text-align: center;\">679<br \/>\n(699)<\/td>\n<td style=\"width: 20%; text-align: center;\">645<br \/>\n(645)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">589<br \/>\n(609)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22256<br \/>\n(25256)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(642)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(606)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">541<br \/>\n(561)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22796<br \/>\n(25796)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(654)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(614)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">551<br \/>\n(571)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23336<br \/>\n(26336)<\/td>\n<td style=\"width: 20%; text-align: center;\">646<br \/>\n(666)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(622)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">561<br \/>\n(581)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24006<br \/>\n(27006)<\/td>\n<td style=\"width: 20%; text-align: center;\">660<br \/>\n(680)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(632)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">573<br \/>\n(593)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24956<br \/>\n(27956)<\/td>\n<td style=\"width: 20%; text-align: center;\">682<br \/>\n(702)<\/td>\n<td style=\"width: 20%; text-align: center;\">646<br \/>\n(646)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">591<br \/>\n(611)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22481<br \/>\n(25481)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(646)<\/td>\n<td style=\"width: 20%; text-align: center;\">608<br \/>\n(608)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">543<br \/>\n(563)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23021<br \/>\n(26021)<\/td>\n<td style=\"width: 20%; text-align: center;\">638<br \/>\n(658)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(616)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">553<br \/>\n(573)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23561<br \/>\n(26561)<\/td>\n<td style=\"width: 20%; text-align: center;\">650<br \/>\n(670)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">563<br \/>\n(583)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24231<br \/>\n(27231)<\/td>\n<td style=\"width: 20%; text-align: center;\">664<br \/>\n(684)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(634)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">575<br \/>\n(595)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25181<br \/>\n(28181)<\/td>\n<td style=\"width: 20%; text-align: center;\">686<br \/>\n(706)<\/td>\n<td style=\"width: 20%; text-align: center;\">648<br \/>\n(648)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">593<br \/>\n(613)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22726<br \/>\n(25726)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(650)<\/td>\n<td style=\"width: 20%; text-align: center;\">610<br \/>\n(610)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">546<br \/>\n(566)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23266<br \/>\n(26266)<\/td>\n<td style=\"width: 20%; text-align: center;\">642<br \/>\n(662)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(618)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">556<br \/>\n(576)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23806<br \/>\n(26806)<\/td>\n<td style=\"width: 20%; text-align: center;\">654<br \/>\n(674)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">566<br \/>\n(586)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24476<br \/>\n(27476)<\/td>\n<td style=\"width: 20%; text-align: center;\">668<br \/>\n(688)<\/td>\n<td style=\"width: 20%; text-align: center;\">636<br \/>\n(636)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">578<br \/>\n(598)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25426<br \/>\n(28426)<\/td>\n<td style=\"width: 20%; text-align: center;\">690<br \/>\n(710)<\/td>\n<td style=\"width: 20%; text-align: center;\">650<br \/>\n(650)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">596<br \/>\n(616)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22991<br \/>\n(25991)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(654)<\/td>\n<td style=\"width: 20%; text-align: center;\">613<br \/>\n(613)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">549<br \/>\n(569)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23531<br \/>\n(26531)<\/td>\n<td style=\"width: 20%; text-align: center;\">646<br \/>\n(666)<\/td>\n<td style=\"width: 20%; text-align: center;\">621<br \/>\n(621)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">559<br \/>\n(579)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24071<br \/>\n(27071)<\/td>\n<td style=\"width: 20%; text-align: center;\">658<br \/>\n(678)<\/td>\n<td style=\"width: 20%; text-align: center;\">629<br \/>\n(629)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">569<br \/>\n(589)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24741<br \/>\n(27741)<\/td>\n<td style=\"width: 20%; text-align: center;\">672<br \/>\n(692)<\/td>\n<td style=\"width: 20%; text-align: center;\">639<br \/>\n(639)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">581<br \/>\n(601)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25691<br \/>\n(28691)<\/td>\n<td style=\"width: 20%; text-align: center;\">694<br \/>\n(714)<\/td>\n<td style=\"width: 20%; text-align: center;\">653<br \/>\n(653)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">599<br \/>\n(619)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23276<br \/>\n(26276)<\/td>\n<td style=\"width: 20%; text-align: center;\">639<br \/>\n(659)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(616)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">553<br \/>\n(573)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23816<br \/>\n(26816)<\/td>\n<td style=\"width: 20%; text-align: center;\">651<br \/>\n(671)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">563<br \/>\n(583)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24356<br \/>\n(27356)<\/td>\n<td style=\"width: 20%; text-align: center;\">663<br \/>\n(683)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(632)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">573<br \/>\n(593)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25026<br \/>\n(28026)<\/td>\n<td style=\"width: 20%; text-align: center;\">677<br \/>\n(697)<\/td>\n<td style=\"width: 20%; text-align: center;\">642<br \/>\n(642)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">585<br \/>\n(605)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25976<br \/>\n(28976)<\/td>\n<td style=\"width: 20%; text-align: center;\">699<br \/>\n(719)<\/td>\n<td style=\"width: 20%; text-align: center;\">656<br \/>\n(656)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">603<br \/>\n(623)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+20 (30)% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<div id=\"FD2\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD2-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-2\"><li class=\"active\"><a class=\"\" href=\"#pane-2-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-2-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21056<br \/>\n(23556)<\/td>\n<td style=\"width: 20%; text-align: center;\">582<br \/>\n(592)<\/td>\n<td style=\"width: 20%; text-align: center;\">574<br \/>\n(604)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">566<br \/>\n(566)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">21596<br \/>\n(24096)<\/td>\n<td style=\"width: 20%; text-align: center;\">594<br \/>\n(604)<\/td>\n<td style=\"width: 20%; text-align: center;\">582<br \/>\n(612)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">576<br \/>\n(576)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22136<br \/>\n(24636)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(616)<\/td>\n<td style=\"width: 20%; text-align: center;\">590<br \/>\n(620)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">586<br \/>\n(586)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">22806<br \/>\n(25306)<\/td>\n<td style=\"width: 20%; text-align: center;\">620<br \/>\n(630)<\/td>\n<td style=\"width: 20%; text-align: center;\">600<br \/>\n(630)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">598<br \/>\n(598)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">23756<br \/>\n(26256)<\/td>\n<td style=\"width: 20%; text-align: center;\">642<br \/>\n(652)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(644)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">616<br \/>\n(616)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21546<br \/>\n(24046)<\/td>\n<td style=\"width: 20%; text-align: center;\">592<br \/>\n(602)<\/td>\n<td style=\"width: 20%; text-align: center;\">582<br \/>\n(612)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">575<br \/>\n(575)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22086<br \/>\n(24586)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(614)<\/td>\n<td style=\"width: 20%; text-align: center;\">590<br \/>\n(620)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">585<br \/>\n(585)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22626<br \/>\n(25126)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(626)<\/td>\n<td style=\"width: 20%; text-align: center;\">598<br \/>\n(628)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">595<br \/>\n(595)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23296<br \/>\n(25796)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(640)<\/td>\n<td style=\"width: 20%; text-align: center;\">608<br \/>\n(638)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">607<br \/>\n(607)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24246<br \/>\n(26746)<\/td>\n<td style=\"width: 20%; text-align: center;\">652<br \/>\n(662)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(652)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">625<br \/>\n(625)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21696<br \/>\n(24196)<\/td>\n<td style=\"width: 20%; text-align: center;\">594<br \/>\n(604)<\/td>\n<td style=\"width: 20%; text-align: center;\">583<br \/>\n(613)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">576<br \/>\n(576)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22236<br \/>\n(24736)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(616)<\/td>\n<td style=\"width: 20%; text-align: center;\">591<br \/>\n(621)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">586<br \/>\n(586)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22776<br \/>\n(25276)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(628)<\/td>\n<td style=\"width: 20%; text-align: center;\">599<br \/>\n(629)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">596<br \/>\n(596)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23446<br \/>\n(25946)<\/td>\n<td style=\"width: 20%; text-align: center;\">632<br \/>\n(642)<\/td>\n<td style=\"width: 20%; text-align: center;\">609<br \/>\n(639)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">608<br \/>\n(608)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24396<br \/>\n(26896)<\/td>\n<td style=\"width: 20%; text-align: center;\">654<br \/>\n(664)<\/td>\n<td style=\"width: 20%; text-align: center;\">623<br \/>\n(653)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">626<br \/>\n(626)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">21866<br \/>\n(24366)<\/td>\n<td style=\"width: 20%; text-align: center;\">596<br \/>\n(606)<\/td>\n<td style=\"width: 20%; text-align: center;\">584<br \/>\n(614)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">577<br \/>\n(577)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22406<br \/>\n(24906)<\/td>\n<td style=\"width: 20%; text-align: center;\">608<br \/>\n(618)<\/td>\n<td style=\"width: 20%; text-align: center;\">592<br \/>\n(622)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">587<br \/>\n(587)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">22946<br \/>\n(25446)<\/td>\n<td style=\"width: 20%; text-align: center;\">620<br \/>\n(630)<\/td>\n<td style=\"width: 20%; text-align: center;\">600<br \/>\n(630)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">597<br \/>\n(597)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23616<br \/>\n(26116)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(644)<\/td>\n<td style=\"width: 20%; text-align: center;\">610<br \/>\n(640)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">609<br \/>\n(609)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24566<br \/>\n(27066)<\/td>\n<td style=\"width: 20%; text-align: center;\">656<br \/>\n(666)<\/td>\n<td style=\"width: 20%; text-align: center;\">624<br \/>\n(654)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">627<br \/>\n(627)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22051<br \/>\n(24551)<\/td>\n<td style=\"width: 20%; text-align: center;\">599<br \/>\n(609)<\/td>\n<td style=\"width: 20%; text-align: center;\">585<br \/>\n(615)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">579<br \/>\n(579)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22591<br \/>\n(25091)<\/td>\n<td style=\"width: 20%; text-align: center;\">611<br \/>\n(621)<\/td>\n<td style=\"width: 20%; text-align: center;\">593<br \/>\n(623)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">589<br \/>\n(589)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23131<br \/>\n(25631)<\/td>\n<td style=\"width: 20%; text-align: center;\">623<br \/>\n(633)<\/td>\n<td style=\"width: 20%; text-align: center;\">601<br \/>\n(631)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">599<br \/>\n(599)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">23801<br \/>\n(26301)<\/td>\n<td style=\"width: 20%; text-align: center;\">637<br \/>\n(647)<\/td>\n<td style=\"width: 20%; text-align: center;\">611<br \/>\n(641)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">611<br \/>\n(611)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24751<br \/>\n(27251)<\/td>\n<td style=\"width: 20%; text-align: center;\">659<br \/>\n(669)<\/td>\n<td style=\"width: 20%; text-align: center;\">625<br \/>\n(655)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">629<br \/>\n(629)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22256<br \/>\n(24756)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(612)<\/td>\n<td style=\"width: 20%; text-align: center;\">586<br \/>\n(616)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">581<br \/>\n(581)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">22796<br \/>\n(25296)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(624)<\/td>\n<td style=\"width: 20%; text-align: center;\">594<br \/>\n(624)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">591<br \/>\n(591)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23336<br \/>\n(25836)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(636)<\/td>\n<td style=\"width: 20%; text-align: center;\">602<br \/>\n(632)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">601<br \/>\n(601)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24006<br \/>\n(26506)<\/td>\n<td style=\"width: 20%; text-align: center;\">640<br \/>\n(650)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(642)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">613<br \/>\n(613)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">24956<br \/>\n(27456)<\/td>\n<td style=\"width: 20%; text-align: center;\">662<br \/>\n(672)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(656)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">631<br \/>\n(631)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22481<br \/>\n(24981)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(616)<\/td>\n<td style=\"width: 20%; text-align: center;\">588<br \/>\n(618)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">583<br \/>\n(583)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23021<br \/>\n(25521)<\/td>\n<td style=\"width: 20%; text-align: center;\">618<br \/>\n(628)<\/td>\n<td style=\"width: 20%; text-align: center;\">596<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">593<br \/>\n(593)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23561<br \/>\n(26061)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(640)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(634)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">603<br \/>\n(603)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24231<br \/>\n(26731)<\/td>\n<td style=\"width: 20%; text-align: center;\">644<br \/>\n(654)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(644)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">615<br \/>\n(615)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25181<br \/>\n(27681)<\/td>\n<td style=\"width: 20%; text-align: center;\">666<br \/>\n(676)<\/td>\n<td style=\"width: 20%; text-align: center;\">628<br \/>\n(658)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">633<br \/>\n(633)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22726<br \/>\n(25226)<\/td>\n<td style=\"width: 20%; text-align: center;\">610<br \/>\n(620)<\/td>\n<td style=\"width: 20%; text-align: center;\">590<br \/>\n(620)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">586<br \/>\n(586)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23266<br \/>\n(25766)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(632)<\/td>\n<td style=\"width: 20%; text-align: center;\">598<br \/>\n(628)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">596<br \/>\n(596)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">23806<br \/>\n(26306)<\/td>\n<td style=\"width: 20%; text-align: center;\">634<br \/>\n(644)<\/td>\n<td style=\"width: 20%; text-align: center;\">606<br \/>\n(636)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">606<br \/>\n(606)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24476<br \/>\n(26976)<\/td>\n<td style=\"width: 20%; text-align: center;\">648<br \/>\n(658)<\/td>\n<td style=\"width: 20%; text-align: center;\">616<br \/>\n(646)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">618<br \/>\n(618)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25426<br \/>\n(27926)<\/td>\n<td style=\"width: 20%; text-align: center;\">670<br \/>\n(680)<\/td>\n<td style=\"width: 20%; text-align: center;\">630<br \/>\n(660)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">636<br \/>\n(636)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">22991<br \/>\n(25491)<\/td>\n<td style=\"width: 20%; text-align: center;\">614<br \/>\n(624)<\/td>\n<td style=\"width: 20%; text-align: center;\">593<br \/>\n(623)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">589<br \/>\n(589)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23531<br \/>\n(26031)<\/td>\n<td style=\"width: 20%; text-align: center;\">626<br \/>\n(636)<\/td>\n<td style=\"width: 20%; text-align: center;\">601<br \/>\n(631)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">599<br \/>\n(599)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24071<br \/>\n(26571)<\/td>\n<td style=\"width: 20%; text-align: center;\">638<br \/>\n(648)<\/td>\n<td style=\"width: 20%; text-align: center;\">609<br \/>\n(639)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">609<br \/>\n(609)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">24741<br \/>\n(27241)<\/td>\n<td style=\"width: 20%; text-align: center;\">652<br \/>\n(662)<\/td>\n<td style=\"width: 20%; text-align: center;\">619<br \/>\n(649)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">621<br \/>\n(621)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25691<br \/>\n(28191)<\/td>\n<td style=\"width: 20%; text-align: center;\">674<br \/>\n(684)<\/td>\n<td style=\"width: 20%; text-align: center;\">633<br \/>\n(663)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">639<br \/>\n(639)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%; border-color: lightgray;\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%;\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%;\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%;\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%;\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%;\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 0<\/th>\n<td style=\"width: 20%; text-align: center;\">23276<br \/>\n(25776)<\/td>\n<td style=\"width: 20%; text-align: center;\">619<br \/>\n(629)<\/td>\n<td style=\"width: 20%; text-align: center;\">596<br \/>\n(626)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">593<br \/>\n(593)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 1<\/th>\n<td style=\"width: 20%; text-align: center;\">23816<br \/>\n(26316)<\/td>\n<td style=\"width: 20%; text-align: center;\">631<br \/>\n(641)<\/td>\n<td style=\"width: 20%; text-align: center;\">604<br \/>\n(634)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">603<br \/>\n(603)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 2<\/th>\n<td style=\"width: 20%; text-align: center;\">24356<br \/>\n(26856)<\/td>\n<td style=\"width: 20%; text-align: center;\">643<br \/>\n(653)<\/td>\n<td style=\"width: 20%; text-align: center;\">612<br \/>\n(642)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">613<br \/>\n(613)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 3<\/th>\n<td style=\"width: 20%; text-align: center;\">25026<br \/>\n(27526)<\/td>\n<td style=\"width: 20%; text-align: center;\">657<br \/>\n(667)<\/td>\n<td style=\"width: 20%; text-align: center;\">622<br \/>\n(652)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">625<br \/>\n(625)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%; vertical-align: middle;\">Limit 4<\/th>\n<td style=\"width: 20%; text-align: center;\">25976<br \/>\n(28476)<\/td>\n<td style=\"width: 20%; text-align: center;\">679<br \/>\n(689)<\/td>\n<td style=\"width: 20%; text-align: center;\">636<br \/>\n(666)<\/td>\n<td style=\"width: 19.7356%; text-align: center;\">643<br \/>\n(643)<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%;\">Special Effect<\/th>\n<td style=\"width: 20%; text-align: center;\" colspan=\"4\">+50 (55)% Increased Status Effect Resistance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<p><span style=\"color: #ff0000; font-size: 10pt;\">\u2022The number between () indicates the stat value at maximum Type Boost<\/span><\/p>\n<h2 class=\"sexypurple\" style=\"text-align: center;\">Normal Attack<\/h2>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 1: Elem-Bullet (\u30a8\u30ec\u30e0\u30d0\u30ec\u30c3\u30c8)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">50 (65)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">2 Different Random Enemies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>Increase own Element Value by 1<\/li>\n<li>30% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Element Halt\" data-contentwrapper=\"osc_popover_1\"> Element Halt <\/button><div id=\"osc_popover_1\" style=\"display:none;\">Cannot gain Element Value for several Turns<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"sexyblue\" style=\"text-align: center;\">\nSkills<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-3\"><li class=\"active\"><a class=\"\" href=\"#pane-3-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-3-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-3-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-3-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Elem-Inspiration (\u30a8\u30ec\u30e0\u30a4\u30f3\u30b9\u30d4\u30ec\u30fc\u30b7\u30e7\u30f3)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Allies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">3<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td style=\"vertical-align: middle;\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Increase Weak Hit damage of All Allies by 40% (2 turns)<\/li>\n<li>Increase Element Gain of All Allies by 50 (100)% (2 Turns)<\/li>\n<\/ol>\n<p>Cool-down: 9 (6) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Elem-Curse (\u30a8\u30ec\u30e0\u30ab\u30fc\u30b9)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">154 (200)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">4<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>50% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Element Halt\" data-contentwrapper=\"osc_popover_2\"> Element Halt <\/button><div id=\"osc_popover_2\" style=\"display:none;\">Cannot gain Element Value for several Turns<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>Increase Weak Hit damage dealt to the Target by 20% (3 turns)<\/li>\n<\/ol>\n<p>Cool-down: 6 (4) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-3-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Elem-Inspiration [Weak Hit Type] (\u30a8\u30ec\u30e0\u30a4\u30f3\u30b9\u30d4\u30ec\u30fc\u30b7\u30e7\u30f3[\u7834])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Allies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">4<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"vertical-align: middle; width: 75%;\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Up (Lower Element)\" data-contentwrapper=\"osc_popover_3\"> Damage Up (Lower Element) <\/button><div id=\"osc_popover_3\" style=\"display:none;\">Increases damage dealt to Targets with less element than you<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 20 (30)% to All Allies (2 turns)<\/li>\n<li>Increase Element Gain of All Allies by 50 (100)% (2 turns)<\/li>\n<li>Increase defense of All Allies by 10 (15)% (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 10 (7) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Elem-Curse [Weak Hit Type] (\u30a8\u30ec\u30e0\u30ab\u30fc\u30b9[\u7834])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">193 (250)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">5<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>50% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Element Halt\" data-contentwrapper=\"osc_popover_4\"> Element Halt <\/button><div id=\"osc_popover_4\" style=\"display:none;\">Cannot gain Element Value for several turns<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>Increase Weak Hit damage dealt to the Target by 20% (3 turns)<\/li>\n<li>When you defeat an Enemy with this attack, increase All Element Values by 2<\/li>\n<\/ol>\n<p>Cool-down: 7 (5) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-3-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Elem-Inspiration [Status Resist Type] (\u30a8\u30ec\u30e0\u30a4\u30f3\u30b9\u30d4\u30ec\u30fc\u30b7\u30e7\u30f3[\u63f4])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">&#8211;<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Allies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">3<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"vertical-align: middle; width: 75%;\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Apply<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Damage Up (Lower Element)\" data-contentwrapper=\"osc_popover_5\"> Damage Up (Lower Element) <\/button><div id=\"osc_popover_5\" style=\"display:none;\">Increases damage dealt to Targets with less element than you<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    of 20 (30)% to All Allies (2 turns)<\/li>\n<li>Increase Element Gain of All Allies by 50 (100)% (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 10 (6) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Elem-Curse [Status Resist Type] (\u30a8\u30ec\u30e0\u30ab\u30fc\u30b9[\u63f4])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">177 (230)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">5<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>50% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Element Halt\" data-contentwrapper=\"osc_popover_6\"> Element Halt <\/button><div id=\"osc_popover_6\" style=\"display:none;\">Cannot gain Element Value for several turns<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>Increase Weak Hit damage dealt to the Target by 20% (3 turns)<\/li>\n<li>When you defeat an Enemy with this attack, reduce All Enemy Element Values by 2<\/li>\n<\/ol>\n<p>Cool-down: 7 (5) turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<h2 class=\"sexyred\" style=\"text-align: center;\">\nElemental Blast<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-4\"><li class=\"active\"><a class=\"\" href=\"#pane-4-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-4-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-4-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-4-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Inscrutable Stratagem (\u795e\u7b97\u9b3c\u8b00)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">272 (380)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">8<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle;\">8<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;\">Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>Reduce Element Gain of the Target by 50% (2 turns)<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-4-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Inscrutable Stratagem [Weak Hit Damage] (\u795e\u7b97\u9b3c\u8b00[\u7834])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">293 (510)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">9<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">9<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>Reduce Element Gain of the Target by 50% (2 turns)<\/li>\n<li>Reduce All Enemy Element Values by 1<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-4-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray; width: 100%;\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%;\" colspan=\"4\">Inscrutable Stratagem [Status Resist Type] (\u795e\u7b97\u9b3c\u8b00[\u63f4])<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Power<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">279 (390)<\/td>\n<th style=\"width: 25%;\">Target<\/th>\n<td style=\"width: 25%; text-align: center; vertical-align: middle;\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%;\">Element Value Req.<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">9<\/td>\n<th style=\"width: 25%;\">Element Value Cost<\/th>\n<td style=\"text-align: center; vertical-align: middle; width: 25%;\">9<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle; width: 25%;\">Effect<\/th>\n<td style=\"width: 75%;\" colspan=\"3\">\n<ol>\n<li>Reduce All Enemy Element Values by 2<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&lt; Back to Characters &nbsp; Kaempfer [Exiled Strategist] (Law) Weak Hit Type Kaempfer [Exiled Strategist] Critical Hit Type Kaempfer [Exiled Strategist] (Chaos) Status Resist Type Rarity Faction Chaos Class Wizard Element Water Idola Andromeda Fates Law Chaos Date 2021\/03\/22 Race Elf Character Stats Default Law Chaos \u2022The number between () indicates the stat value at [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":567,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-7926","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PatEj8-23Q","_links":{"self":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/7926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/comments?post=7926"}],"version-history":[{"count":3,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/7926\/revisions"}],"predecessor-version":[{"id":8980,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/7926\/revisions\/8980"}],"up":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/567"}],"wp:attachment":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/media?parent=7926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}