{"id":6051,"date":"2020-06-02T18:42:39","date_gmt":"2020-06-02T22:42:39","guid":{"rendered":"https:\/\/bumped.org\/idola\/?page_id=6051"},"modified":"2020-06-02T18:42:39","modified_gmt":"2020-06-02T22:42:39","slug":"character-luke","status":"publish","type":"page","link":"https:\/\/bumped.org\/idola\/idola-character-database\/character-luke\/","title":{"rendered":"Character: Luke"},"content":{"rendered":"<p><a href=\"https:\/\/bumped.org\/idola\/idola-character-database\/\">&lt; Back to Characters<\/a><\/p>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-law.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6052 size-medium\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-law.png?resize=273%2C300&#038;ssl=1\" alt=\"\" width=\"273\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-law.png?resize=273%2C300&amp;ssl=1 273w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-law.png?resize=768%2C844&amp;ssl=1 768w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-law.png?w=887&amp;ssl=1 887w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/><\/a><\/td>\n<td style=\"width: 33.3333%\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6054 size-medium\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke.png?resize=273%2C300&#038;ssl=1\" alt=\"\" width=\"273\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke.png?resize=273%2C300&amp;ssl=1 273w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke.png?resize=768%2C843&amp;ssl=1 768w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke.png?w=927&amp;ssl=1 927w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/><\/a><\/td>\n<td style=\"width: 33.3333%\"><a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-chaos.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6053 size-medium\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-chaos.png?resize=283%2C300&#038;ssl=1\" alt=\"\" width=\"283\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-chaos.png?resize=283%2C300&amp;ssl=1 283w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-chaos.png?resize=768%2C814&amp;ssl=1 768w, https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/06\/character-luke-chaos.png?w=955&amp;ssl=1 955w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 33.3333%;text-align: center\">\n<p>Luke (Law)<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-weak-hit-damage.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5886\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-weak-hit-damage.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Weak Hit Type<\/p>\n<\/th>\n<th style=\"width: 33.3333%;text-align: center\">Luke<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-attack.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-5889 alignnone\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/Type-attack.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Attack Type<\/th>\n<th style=\"width: 33.3333%;text-align: center\">Luke (Chaos)<br \/>\n<a href=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/type-critical-hit-rate.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-5884 alignnone\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2020\/05\/type-critical-hit-rate.png?resize=24%2C24&#038;ssl=1\" alt=\"\" width=\"24\" height=\"24\" \/><\/a> Critical Hit Type<\/th>\n<\/tr>\n<\/tbody>\n<\/table>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 100%;border-color: #757575\" border=\"1\" width=\"100%\">\n<thead>\n<tr>\n<td style=\"background-color: #e3e3e3;width: 20%;border-color: grey;text-align: center;vertical-align: middle\" width=\"20%\">Rarity<\/td>\n<td style=\"border-color: grey;vertical-align: middle\" width=\"30%\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/misc-icon-star-e1543540001616.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/><\/td>\n<td style=\"border-color: grey;background-color: #e3e3e3;width: 20%;text-align: center;vertical-align: middle\" width=\"20%\">Faction<\/td>\n<td style=\"border-color: grey;vertical-align: middle\" width=\"30%\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1280\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Chaos-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Chaos<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"border-color: #757575\">\n<td style=\"border-color: grey;background-color: #e3e3e3;text-align: center;vertical-align: middle\">Class<\/td>\n<td style=\"border-color: grey;vertical-align: middle\">Assassin<\/td>\n<td style=\"border-color: grey;background-color: #e3e3e3;text-align: center;vertical-align: middle\">Element<\/td>\n<td style=\"border-color: grey;vertical-align: middle\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1004\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/element-icon-water-e1543528071903.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Water<\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: grey;background-color: #e3e3e3;text-align: center;vertical-align: middle\">Idola<\/td>\n<td style=\"border-color: grey;vertical-align: middle\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1079\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/idola-icon-7-e1543537574755.png?resize=17%2C22&#038;ssl=1\" alt=\"\" width=\"17\" height=\"22\" \/> Lupus<\/td>\n<td style=\"border-color: grey;background-color: #e3e3e3;text-align: center;vertical-align: middle\">Fates<\/td>\n<td style=\"border-color: grey;vertical-align: middle\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1281\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Law-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Law<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1280\" style=\"vertical-align: middle\" src=\"https:\/\/i0.wp.com\/bumped.org\/idola\/wp-content\/uploads\/2018\/11\/Chaos-Icon.png?resize=20%2C20&#038;ssl=1\" alt=\"\" width=\"20\" height=\"20\" \/> Chaos<\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: grey;background-color: #e3e3e3;text-align: center;vertical-align: middle\">Date<\/td>\n<td style=\"border-color: grey;vertical-align: middle\">2020\/06\/01<\/td>\n<td style=\"border-color: grey;background-color: #e3e3e3;text-align: center;vertical-align: middle\">Race<\/td>\n<td style=\"border-color: grey;vertical-align: middle\">Human<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"sexyblue\" style=\"text-align: center\">Character Stats<\/h2>\n<ul id=\"DBLimits\" class=\"nav nav-tabs\" role=\"tablist\">\n<li class=\"nav-item\"><a id=\"limi0-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD0\" data-toggle=\"tab\">Default<\/a><\/li>\n<li class=\"nav-item\"><a id=\"limi1-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD1\" data-toggle=\"tab\">Law<\/a><\/li>\n<li class=\"nav-item\"><a id=\"limi2-tab\" class=\"nav-link\" role=\"tab\" href=\"#FD2\" data-toggle=\"tab\">Chaos<\/a><\/li>\n<\/ul>\n<div id=\"DBStats\" class=\"tab-content small\">\n<div id=\"FD0\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD0-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-0\"><li class=\"active\"><a class=\"\" href=\"#pane-0-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-0-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-0-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20009<\/td>\n<td style=\"width: 20%;text-align: center\">579<\/td>\n<td style=\"width: 20%;text-align: center\">545<\/td>\n<td style=\"width: 19.7356%;text-align: center\">529<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">20549<\/td>\n<td style=\"width: 20%;text-align: center\">590<\/td>\n<td style=\"width: 20%;text-align: center\">553<\/td>\n<td style=\"width: 19.7356%;text-align: center\">540<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21089<\/td>\n<td style=\"width: 20%;text-align: center\">601<\/td>\n<td style=\"width: 20%;text-align: center\">561<\/td>\n<td style=\"width: 19.7356%;text-align: center\">551<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">21759<\/td>\n<td style=\"width: 20%;text-align: center\">614<\/td>\n<td style=\"width: 20%;text-align: center\">571<\/td>\n<td style=\"width: 19.7356%;text-align: center\">564<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">22709<\/td>\n<td style=\"width: 20%;text-align: center\">634<\/td>\n<td style=\"width: 20%;text-align: center\">585<\/td>\n<td style=\"width: 19.7356%;text-align: center\">584<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20509<\/td>\n<td style=\"width: 20%;text-align: center\">589<\/td>\n<td style=\"width: 20%;text-align: center\">552<\/td>\n<td style=\"width: 19.7356%;text-align: center\">539<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21049<\/td>\n<td style=\"width: 20%;text-align: center\">600<\/td>\n<td style=\"width: 20%;text-align: center\">560<\/td>\n<td style=\"width: 19.7356%;text-align: center\">550<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21589<\/td>\n<td style=\"width: 20%;text-align: center\">611<\/td>\n<td style=\"width: 20%;text-align: center\">568<\/td>\n<td style=\"width: 19.7356%;text-align: center\">561<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22259<\/td>\n<td style=\"width: 20%;text-align: center\">624<\/td>\n<td style=\"width: 20%;text-align: center\">578<\/td>\n<td style=\"width: 19.7356%;text-align: center\">574<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23209<\/td>\n<td style=\"width: 20%;text-align: center\">644<\/td>\n<td style=\"width: 20%;text-align: center\">592<\/td>\n<td style=\"width: 19.7356%;text-align: center\">594<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20666<\/td>\n<td style=\"width: 20%;text-align: center\">591<\/td>\n<td style=\"width: 20%;text-align: center\">553<\/td>\n<td style=\"width: 19.7356%;text-align: center\">541<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21206<\/td>\n<td style=\"width: 20%;text-align: center\">602<\/td>\n<td style=\"width: 20%;text-align: center\">561<\/td>\n<td style=\"width: 19.7356%;text-align: center\">552<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21746<\/td>\n<td style=\"width: 20%;text-align: center\">613<\/td>\n<td style=\"width: 20%;text-align: center\">569<\/td>\n<td style=\"width: 19.7356%;text-align: center\">563<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22416<\/td>\n<td style=\"width: 20%;text-align: center\">626<\/td>\n<td style=\"width: 20%;text-align: center\">579<\/td>\n<td style=\"width: 19.7356%;text-align: center\">576<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23366<\/td>\n<td style=\"width: 20%;text-align: center\">646<\/td>\n<td style=\"width: 20%;text-align: center\">593<\/td>\n<td style=\"width: 19.7356%;text-align: center\">596<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20846<\/td>\n<td style=\"width: 20%;text-align: center\">594<\/td>\n<td style=\"width: 20%;text-align: center\">554<\/td>\n<td style=\"width: 19.7356%;text-align: center\">544<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21386<\/td>\n<td style=\"width: 20%;text-align: center\">605<\/td>\n<td style=\"width: 20%;text-align: center\">562<\/td>\n<td style=\"width: 19.7356%;text-align: center\">555<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21926<\/td>\n<td style=\"width: 20%;text-align: center\">616<\/td>\n<td style=\"width: 20%;text-align: center\">570<\/td>\n<td style=\"width: 19.7356%;text-align: center\">566<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22596<\/td>\n<td style=\"width: 20%;text-align: center\">629<\/td>\n<td style=\"width: 20%;text-align: center\">580<\/td>\n<td style=\"width: 19.7356%;text-align: center\">579<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23546<\/td>\n<td style=\"width: 20%;text-align: center\">649<\/td>\n<td style=\"width: 20%;text-align: center\">594<\/td>\n<td style=\"width: 19.7356%;text-align: center\">599<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21036<\/td>\n<td style=\"width: 20%;text-align: center\">597<\/td>\n<td style=\"width: 20%;text-align: center\">555<\/td>\n<td style=\"width: 19.7356%;text-align: center\">547<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21576<\/td>\n<td style=\"width: 20%;text-align: center\">608<\/td>\n<td style=\"width: 20%;text-align: center\">563<\/td>\n<td style=\"width: 19.7356%;text-align: center\">558<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22116<\/td>\n<td style=\"width: 20%;text-align: center\">619<\/td>\n<td style=\"width: 20%;text-align: center\">571<\/td>\n<td style=\"width: 19.7356%;text-align: center\">569<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22786<\/td>\n<td style=\"width: 20%;text-align: center\">632<\/td>\n<td style=\"width: 20%;text-align: center\">581<\/td>\n<td style=\"width: 19.7356%;text-align: center\">582<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23736<\/td>\n<td style=\"width: 20%;text-align: center\">652<\/td>\n<td style=\"width: 20%;text-align: center\">595<\/td>\n<td style=\"width: 19.7356%;text-align: center\">602<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21239<\/td>\n<td style=\"width: 20%;text-align: center\">600<\/td>\n<td style=\"width: 20%;text-align: center\">556<\/td>\n<td style=\"width: 19.7356%;text-align: center\">550<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21779<\/td>\n<td style=\"width: 20%;text-align: center\">611<\/td>\n<td style=\"width: 20%;text-align: center\">564<\/td>\n<td style=\"width: 19.7356%;text-align: center\">561<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22319<\/td>\n<td style=\"width: 20%;text-align: center\">622<\/td>\n<td style=\"width: 20%;text-align: center\">572<\/td>\n<td style=\"width: 19.7356%;text-align: center\">572<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22989<\/td>\n<td style=\"width: 20%;text-align: center\">635<\/td>\n<td style=\"width: 20%;text-align: center\">582<\/td>\n<td style=\"width: 19.7356%;text-align: center\">585<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23939<\/td>\n<td style=\"width: 20%;text-align: center\">655<\/td>\n<td style=\"width: 20%;text-align: center\">596<\/td>\n<td style=\"width: 19.7356%;text-align: center\">605<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21456<\/td>\n<td style=\"width: 20%;text-align: center\">603<\/td>\n<td style=\"width: 20%;text-align: center\">557<\/td>\n<td style=\"width: 19.7356%;text-align: center\">553<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21996<\/td>\n<td style=\"width: 20%;text-align: center\">614<\/td>\n<td style=\"width: 20%;text-align: center\">565<\/td>\n<td style=\"width: 19.7356%;text-align: center\">564<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22536<\/td>\n<td style=\"width: 20%;text-align: center\">625<\/td>\n<td style=\"width: 20%;text-align: center\">573<\/td>\n<td style=\"width: 19.7356%;text-align: center\">575<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23206<\/td>\n<td style=\"width: 20%;text-align: center\">638<\/td>\n<td style=\"width: 20%;text-align: center\">583<\/td>\n<td style=\"width: 19.7356%;text-align: center\">588<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24156<\/td>\n<td style=\"width: 20%;text-align: center\">658<\/td>\n<td style=\"width: 20%;text-align: center\">597<\/td>\n<td style=\"width: 19.7356%;text-align: center\">608<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21684<\/td>\n<td style=\"width: 20%;text-align: center\">607<\/td>\n<td style=\"width: 20%;text-align: center\">558<\/td>\n<td style=\"width: 19.7356%;text-align: center\">557<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22224<\/td>\n<td style=\"width: 20%;text-align: center\">618<\/td>\n<td style=\"width: 20%;text-align: center\">566<\/td>\n<td style=\"width: 19.7356%;text-align: center\">568<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22764<\/td>\n<td style=\"width: 20%;text-align: center\">629<\/td>\n<td style=\"width: 20%;text-align: center\">574<\/td>\n<td style=\"width: 19.7356%;text-align: center\">579<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23434<\/td>\n<td style=\"width: 20%;text-align: center\">642<\/td>\n<td style=\"width: 20%;text-align: center\">584<\/td>\n<td style=\"width: 19.7356%;text-align: center\">592<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24384<\/td>\n<td style=\"width: 20%;text-align: center\">662<\/td>\n<td style=\"width: 20%;text-align: center\">598<\/td>\n<td style=\"width: 19.7356%;text-align: center\">612<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21929<\/td>\n<td style=\"width: 20%;text-align: center\">611<\/td>\n<td style=\"width: 20%;text-align: center\">559<\/td>\n<td style=\"width: 19.7356%;text-align: center\">561<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22469<\/td>\n<td style=\"width: 20%;text-align: center\">622<\/td>\n<td style=\"width: 20%;text-align: center\">567<\/td>\n<td style=\"width: 19.7356%;text-align: center\">572<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">23009<\/td>\n<td style=\"width: 20%;text-align: center\">633<\/td>\n<td style=\"width: 20%;text-align: center\">575<\/td>\n<td style=\"width: 19.7356%;text-align: center\">583<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23679<\/td>\n<td style=\"width: 20%;text-align: center\">646<\/td>\n<td style=\"width: 20%;text-align: center\">585<\/td>\n<td style=\"width: 19.7356%;text-align: center\">596<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24629<\/td>\n<td style=\"width: 20%;text-align: center\">666<\/td>\n<td style=\"width: 20%;text-align: center\">599<\/td>\n<td style=\"width: 19.7356%;text-align: center\">616<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-0-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">22194<\/td>\n<td style=\"width: 20%;text-align: center\">615<\/td>\n<td style=\"width: 20%;text-align: center\">561<\/td>\n<td style=\"width: 19.7356%;text-align: center\">565<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22734<\/td>\n<td style=\"width: 20%;text-align: center\">626<\/td>\n<td style=\"width: 20%;text-align: center\">569<\/td>\n<td style=\"width: 19.7356%;text-align: center\">576<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">23274<\/td>\n<td style=\"width: 20%;text-align: center\">637<\/td>\n<td style=\"width: 20%;text-align: center\">577<\/td>\n<td style=\"width: 19.7356%;text-align: center\">587<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23944<\/td>\n<td style=\"width: 20%;text-align: center\">650<\/td>\n<td style=\"width: 20%;text-align: center\">587<\/td>\n<td style=\"width: 19.7356%;text-align: center\">600<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24894<\/td>\n<td style=\"width: 20%;text-align: center\">670<\/td>\n<td style=\"width: 20%;text-align: center\">601<\/td>\n<td style=\"width: 19.7356%;text-align: center\">620<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<div id=\"FD1\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD1-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-1\"><li class=\"active\"><a class=\"\" href=\"#pane-1-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-1-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-1-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">19809<\/td>\n<td style=\"width: 20%;text-align: center\">539<\/td>\n<td style=\"width: 20%;text-align: center\">565<\/td>\n<td style=\"width: 19.7356%;text-align: center\">549<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">20349<\/td>\n<td style=\"width: 20%;text-align: center\">550<\/td>\n<td style=\"width: 20%;text-align: center\">573<\/td>\n<td style=\"width: 19.7356%;text-align: center\">560<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">20889<\/td>\n<td style=\"width: 20%;text-align: center\">561<\/td>\n<td style=\"width: 20%;text-align: center\">581<\/td>\n<td style=\"width: 19.7356%;text-align: center\">571<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">21559<\/td>\n<td style=\"width: 20%;text-align: center\">574<\/td>\n<td style=\"width: 20%;text-align: center\">591<\/td>\n<td style=\"width: 19.7356%;text-align: center\">584<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">22509<\/td>\n<td style=\"width: 20%;text-align: center\">594<\/td>\n<td style=\"width: 20%;text-align: center\">605<\/td>\n<td style=\"width: 19.7356%;text-align: center\">604<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20309<\/td>\n<td style=\"width: 20%;text-align: center\">549<\/td>\n<td style=\"width: 20%;text-align: center\">572<\/td>\n<td style=\"width: 19.7356%;text-align: center\">559<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">20849<\/td>\n<td style=\"width: 20%;text-align: center\">560<\/td>\n<td style=\"width: 20%;text-align: center\">580<\/td>\n<td style=\"width: 19.7356%;text-align: center\">570<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21389<\/td>\n<td style=\"width: 20%;text-align: center\">571<\/td>\n<td style=\"width: 20%;text-align: center\">588<\/td>\n<td style=\"width: 19.7356%;text-align: center\">581<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22059<\/td>\n<td style=\"width: 20%;text-align: center\">584<\/td>\n<td style=\"width: 20%;text-align: center\">598<\/td>\n<td style=\"width: 19.7356%;text-align: center\">594<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23009<\/td>\n<td style=\"width: 20%;text-align: center\">604<\/td>\n<td style=\"width: 20%;text-align: center\">612<\/td>\n<td style=\"width: 19.7356%;text-align: center\">614<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20466<\/td>\n<td style=\"width: 20%;text-align: center\">551<\/td>\n<td style=\"width: 20%;text-align: center\">573<\/td>\n<td style=\"width: 19.7356%;text-align: center\">561<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21006<\/td>\n<td style=\"width: 20%;text-align: center\">562<\/td>\n<td style=\"width: 20%;text-align: center\">581<\/td>\n<td style=\"width: 19.7356%;text-align: center\">572<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21546<\/td>\n<td style=\"width: 20%;text-align: center\">573<\/td>\n<td style=\"width: 20%;text-align: center\">589<\/td>\n<td style=\"width: 19.7356%;text-align: center\">583<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22216<\/td>\n<td style=\"width: 20%;text-align: center\">586<\/td>\n<td style=\"width: 20%;text-align: center\">599<\/td>\n<td style=\"width: 19.7356%;text-align: center\">596<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23166<\/td>\n<td style=\"width: 20%;text-align: center\">606<\/td>\n<td style=\"width: 20%;text-align: center\">613<\/td>\n<td style=\"width: 19.7356%;text-align: center\">616<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20646<\/td>\n<td style=\"width: 20%;text-align: center\">554<\/td>\n<td style=\"width: 20%;text-align: center\">574<\/td>\n<td style=\"width: 19.7356%;text-align: center\">564<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21186<\/td>\n<td style=\"width: 20%;text-align: center\">565<\/td>\n<td style=\"width: 20%;text-align: center\">582<\/td>\n<td style=\"width: 19.7356%;text-align: center\">575<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21726<\/td>\n<td style=\"width: 20%;text-align: center\">576<\/td>\n<td style=\"width: 20%;text-align: center\">590<\/td>\n<td style=\"width: 19.7356%;text-align: center\">586<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22396<\/td>\n<td style=\"width: 20%;text-align: center\">589<\/td>\n<td style=\"width: 20%;text-align: center\">600<\/td>\n<td style=\"width: 19.7356%;text-align: center\">599<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23346<\/td>\n<td style=\"width: 20%;text-align: center\">609<\/td>\n<td style=\"width: 20%;text-align: center\">614<\/td>\n<td style=\"width: 19.7356%;text-align: center\">619<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20836<\/td>\n<td style=\"width: 20%;text-align: center\">557<\/td>\n<td style=\"width: 20%;text-align: center\">575<\/td>\n<td style=\"width: 19.7356%;text-align: center\">567<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21376<\/td>\n<td style=\"width: 20%;text-align: center\">568<\/td>\n<td style=\"width: 20%;text-align: center\">583<\/td>\n<td style=\"width: 19.7356%;text-align: center\">578<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21916<\/td>\n<td style=\"width: 20%;text-align: center\">579<\/td>\n<td style=\"width: 20%;text-align: center\">591<\/td>\n<td style=\"width: 19.7356%;text-align: center\">589<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22586<\/td>\n<td style=\"width: 20%;text-align: center\">592<\/td>\n<td style=\"width: 20%;text-align: center\">601<\/td>\n<td style=\"width: 19.7356%;text-align: center\">602<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23536<\/td>\n<td style=\"width: 20%;text-align: center\">612<\/td>\n<td style=\"width: 20%;text-align: center\">615<\/td>\n<td style=\"width: 19.7356%;text-align: center\">622<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21039<\/td>\n<td style=\"width: 20%;text-align: center\">560<\/td>\n<td style=\"width: 20%;text-align: center\">576<\/td>\n<td style=\"width: 19.7356%;text-align: center\">570<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21579<\/td>\n<td style=\"width: 20%;text-align: center\">571<\/td>\n<td style=\"width: 20%;text-align: center\">584<\/td>\n<td style=\"width: 19.7356%;text-align: center\">581<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22119<\/td>\n<td style=\"width: 20%;text-align: center\">582<\/td>\n<td style=\"width: 20%;text-align: center\">592<\/td>\n<td style=\"width: 19.7356%;text-align: center\">592<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22789<\/td>\n<td style=\"width: 20%;text-align: center\">595<\/td>\n<td style=\"width: 20%;text-align: center\">602<\/td>\n<td style=\"width: 19.7356%;text-align: center\">605<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23739<\/td>\n<td style=\"width: 20%;text-align: center\">615<\/td>\n<td style=\"width: 20%;text-align: center\">616<\/td>\n<td style=\"width: 19.7356%;text-align: center\">625<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21256<\/td>\n<td style=\"width: 20%;text-align: center\">563<\/td>\n<td style=\"width: 20%;text-align: center\">577<\/td>\n<td style=\"width: 19.7356%;text-align: center\">573<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21796<\/td>\n<td style=\"width: 20%;text-align: center\">574<\/td>\n<td style=\"width: 20%;text-align: center\">585<\/td>\n<td style=\"width: 19.7356%;text-align: center\">584<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22336<\/td>\n<td style=\"width: 20%;text-align: center\">585<\/td>\n<td style=\"width: 20%;text-align: center\">593<\/td>\n<td style=\"width: 19.7356%;text-align: center\">595<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23006<\/td>\n<td style=\"width: 20%;text-align: center\">598<\/td>\n<td style=\"width: 20%;text-align: center\">603<\/td>\n<td style=\"width: 19.7356%;text-align: center\">608<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23956<\/td>\n<td style=\"width: 20%;text-align: center\">618<\/td>\n<td style=\"width: 20%;text-align: center\">617<\/td>\n<td style=\"width: 19.7356%;text-align: center\">628<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21484<\/td>\n<td style=\"width: 20%;text-align: center\">567<\/td>\n<td style=\"width: 20%;text-align: center\">578<\/td>\n<td style=\"width: 19.7356%;text-align: center\">577<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22024<\/td>\n<td style=\"width: 20%;text-align: center\">578<\/td>\n<td style=\"width: 20%;text-align: center\">586<\/td>\n<td style=\"width: 19.7356%;text-align: center\">588<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22564<\/td>\n<td style=\"width: 20%;text-align: center\">589<\/td>\n<td style=\"width: 20%;text-align: center\">594<\/td>\n<td style=\"width: 19.7356%;text-align: center\">599<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23234<\/td>\n<td style=\"width: 20%;text-align: center\">602<\/td>\n<td style=\"width: 20%;text-align: center\">604<\/td>\n<td style=\"width: 19.7356%;text-align: center\">612<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24184<\/td>\n<td style=\"width: 20%;text-align: center\">622<\/td>\n<td style=\"width: 20%;text-align: center\">618<\/td>\n<td style=\"width: 19.7356%;text-align: center\">632<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21729<\/td>\n<td style=\"width: 20%;text-align: center\">571<\/td>\n<td style=\"width: 20%;text-align: center\">579<\/td>\n<td style=\"width: 19.7356%;text-align: center\">581<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22269<\/td>\n<td style=\"width: 20%;text-align: center\">582<\/td>\n<td style=\"width: 20%;text-align: center\">587<\/td>\n<td style=\"width: 19.7356%;text-align: center\">592<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22809<\/td>\n<td style=\"width: 20%;text-align: center\">593<\/td>\n<td style=\"width: 20%;text-align: center\">595<\/td>\n<td style=\"width: 19.7356%;text-align: center\">603<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23479<\/td>\n<td style=\"width: 20%;text-align: center\">606<\/td>\n<td style=\"width: 20%;text-align: center\">605<\/td>\n<td style=\"width: 19.7356%;text-align: center\">616<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24429<\/td>\n<td style=\"width: 20%;text-align: center\">626<\/td>\n<td style=\"width: 20%;text-align: center\">619<\/td>\n<td style=\"width: 19.7356%;text-align: center\">636<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-1-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21994<\/td>\n<td style=\"width: 20%;text-align: center\">575<\/td>\n<td style=\"width: 20%;text-align: center\">581<\/td>\n<td style=\"width: 19.7356%;text-align: center\">585<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22534<\/td>\n<td style=\"width: 20%;text-align: center\">586<\/td>\n<td style=\"width: 20%;text-align: center\">589<\/td>\n<td style=\"width: 19.7356%;text-align: center\">596<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">23074<\/td>\n<td style=\"width: 20%;text-align: center\">597<\/td>\n<td style=\"width: 20%;text-align: center\">597<\/td>\n<td style=\"width: 19.7356%;text-align: center\">607<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23744<\/td>\n<td style=\"width: 20%;text-align: center\">610<\/td>\n<td style=\"width: 20%;text-align: center\">607<\/td>\n<td style=\"width: 19.7356%;text-align: center\">620<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24694<\/td>\n<td style=\"width: 20%;text-align: center\">630<\/td>\n<td style=\"width: 20%;text-align: center\">621<\/td>\n<td style=\"width: 19.7356%;text-align: center\">640<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+20% Increased Weak Hit Damage<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<div id=\"FD2\" class=\"tab-pane fade active\" role=\"tabpanel\" aria-labelledby=\"FD2-tab\">\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-2\"><li class=\"active\"><a class=\"\" href=\"#pane-2-0\" data-toggle=\"tab\">No DB<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-1\" data-toggle=\"tab\">DB0<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-2\" data-toggle=\"tab\">DB1<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-3\" data-toggle=\"tab\">DB2<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-4\" data-toggle=\"tab\">DB3<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-5\" data-toggle=\"tab\">DB4<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-6\" data-toggle=\"tab\">DB5<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-7\" data-toggle=\"tab\">DB6<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-8\" data-toggle=\"tab\">DB7<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-2-9\" data-toggle=\"tab\">DBMAX<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-2-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">19809<\/td>\n<td style=\"width: 20%;text-align: center\">499<\/td>\n<td style=\"width: 20%;text-align: center\">545<\/td>\n<td style=\"width: 19.7356%;text-align: center\">599<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">20349<\/td>\n<td style=\"width: 20%;text-align: center\">510<\/td>\n<td style=\"width: 20%;text-align: center\">553<\/td>\n<td style=\"width: 19.7356%;text-align: center\">610<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">20889<\/td>\n<td style=\"width: 20%;text-align: center\">521<\/td>\n<td style=\"width: 20%;text-align: center\">561<\/td>\n<td style=\"width: 19.7356%;text-align: center\">621<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">21559<\/td>\n<td style=\"width: 20%;text-align: center\">534<\/td>\n<td style=\"width: 20%;text-align: center\">571<\/td>\n<td style=\"width: 19.7356%;text-align: center\">634<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">22509<\/td>\n<td style=\"width: 20%;text-align: center\">554<\/td>\n<td style=\"width: 20%;text-align: center\">585<\/td>\n<td style=\"width: 19.7356%;text-align: center\">654<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20309<\/td>\n<td style=\"width: 20%;text-align: center\">509<\/td>\n<td style=\"width: 20%;text-align: center\">552<\/td>\n<td style=\"width: 19.7356%;text-align: center\">609<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">20849<\/td>\n<td style=\"width: 20%;text-align: center\">520<\/td>\n<td style=\"width: 20%;text-align: center\">560<\/td>\n<td style=\"width: 19.7356%;text-align: center\">620<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21389<\/td>\n<td style=\"width: 20%;text-align: center\">531<\/td>\n<td style=\"width: 20%;text-align: center\">568<\/td>\n<td style=\"width: 19.7356%;text-align: center\">631<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22059<\/td>\n<td style=\"width: 20%;text-align: center\">544<\/td>\n<td style=\"width: 20%;text-align: center\">578<\/td>\n<td style=\"width: 19.7356%;text-align: center\">644<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23009<\/td>\n<td style=\"width: 20%;text-align: center\">564<\/td>\n<td style=\"width: 20%;text-align: center\">592<\/td>\n<td style=\"width: 19.7356%;text-align: center\">664<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20466<\/td>\n<td style=\"width: 20%;text-align: center\">511<\/td>\n<td style=\"width: 20%;text-align: center\">553<\/td>\n<td style=\"width: 19.7356%;text-align: center\">611<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21006<\/td>\n<td style=\"width: 20%;text-align: center\">522<\/td>\n<td style=\"width: 20%;text-align: center\">561<\/td>\n<td style=\"width: 19.7356%;text-align: center\">622<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21546<\/td>\n<td style=\"width: 20%;text-align: center\">533<\/td>\n<td style=\"width: 20%;text-align: center\">569<\/td>\n<td style=\"width: 19.7356%;text-align: center\">633<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22216<\/td>\n<td style=\"width: 20%;text-align: center\">546<\/td>\n<td style=\"width: 20%;text-align: center\">579<\/td>\n<td style=\"width: 19.7356%;text-align: center\">646<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23166<\/td>\n<td style=\"width: 20%;text-align: center\">566<\/td>\n<td style=\"width: 20%;text-align: center\">593<\/td>\n<td style=\"width: 19.7356%;text-align: center\">666<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-3\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20646<\/td>\n<td style=\"width: 20%;text-align: center\">514<\/td>\n<td style=\"width: 20%;text-align: center\">554<\/td>\n<td style=\"width: 19.7356%;text-align: center\">614<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21186<\/td>\n<td style=\"width: 20%;text-align: center\">525<\/td>\n<td style=\"width: 20%;text-align: center\">562<\/td>\n<td style=\"width: 19.7356%;text-align: center\">625<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21726<\/td>\n<td style=\"width: 20%;text-align: center\">536<\/td>\n<td style=\"width: 20%;text-align: center\">570<\/td>\n<td style=\"width: 19.7356%;text-align: center\">636<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22396<\/td>\n<td style=\"width: 20%;text-align: center\">549<\/td>\n<td style=\"width: 20%;text-align: center\">580<\/td>\n<td style=\"width: 19.7356%;text-align: center\">649<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23346<\/td>\n<td style=\"width: 20%;text-align: center\">569<\/td>\n<td style=\"width: 20%;text-align: center\">594<\/td>\n<td style=\"width: 19.7356%;text-align: center\">669<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-4\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">20836<\/td>\n<td style=\"width: 20%;text-align: center\">517<\/td>\n<td style=\"width: 20%;text-align: center\">555<\/td>\n<td style=\"width: 19.7356%;text-align: center\">617<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21376<\/td>\n<td style=\"width: 20%;text-align: center\">528<\/td>\n<td style=\"width: 20%;text-align: center\">563<\/td>\n<td style=\"width: 19.7356%;text-align: center\">628<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">21916<\/td>\n<td style=\"width: 20%;text-align: center\">539<\/td>\n<td style=\"width: 20%;text-align: center\">571<\/td>\n<td style=\"width: 19.7356%;text-align: center\">639<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22586<\/td>\n<td style=\"width: 20%;text-align: center\">552<\/td>\n<td style=\"width: 20%;text-align: center\">581<\/td>\n<td style=\"width: 19.7356%;text-align: center\">652<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23536<\/td>\n<td style=\"width: 20%;text-align: center\">572<\/td>\n<td style=\"width: 20%;text-align: center\">595<\/td>\n<td style=\"width: 19.7356%;text-align: center\">672<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-5\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21039<\/td>\n<td style=\"width: 20%;text-align: center\">520<\/td>\n<td style=\"width: 20%;text-align: center\">556<\/td>\n<td style=\"width: 19.7356%;text-align: center\">620<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21579<\/td>\n<td style=\"width: 20%;text-align: center\">531<\/td>\n<td style=\"width: 20%;text-align: center\">564<\/td>\n<td style=\"width: 19.7356%;text-align: center\">631<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22119<\/td>\n<td style=\"width: 20%;text-align: center\">542<\/td>\n<td style=\"width: 20%;text-align: center\">572<\/td>\n<td style=\"width: 19.7356%;text-align: center\">642<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">22789<\/td>\n<td style=\"width: 20%;text-align: center\">555<\/td>\n<td style=\"width: 20%;text-align: center\">582<\/td>\n<td style=\"width: 19.7356%;text-align: center\">655<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23739<\/td>\n<td style=\"width: 20%;text-align: center\">575<\/td>\n<td style=\"width: 20%;text-align: center\">596<\/td>\n<td style=\"width: 19.7356%;text-align: center\">675<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-6\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21256<\/td>\n<td style=\"width: 20%;text-align: center\">523<\/td>\n<td style=\"width: 20%;text-align: center\">557<\/td>\n<td style=\"width: 19.7356%;text-align: center\">623<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">21796<\/td>\n<td style=\"width: 20%;text-align: center\">534<\/td>\n<td style=\"width: 20%;text-align: center\">565<\/td>\n<td style=\"width: 19.7356%;text-align: center\">634<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22336<\/td>\n<td style=\"width: 20%;text-align: center\">545<\/td>\n<td style=\"width: 20%;text-align: center\">573<\/td>\n<td style=\"width: 19.7356%;text-align: center\">645<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23006<\/td>\n<td style=\"width: 20%;text-align: center\">558<\/td>\n<td style=\"width: 20%;text-align: center\">583<\/td>\n<td style=\"width: 19.7356%;text-align: center\">658<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">23956<\/td>\n<td style=\"width: 20%;text-align: center\">578<\/td>\n<td style=\"width: 20%;text-align: center\">597<\/td>\n<td style=\"width: 19.7356%;text-align: center\">678<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-7\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21484<\/td>\n<td style=\"width: 20%;text-align: center\">527<\/td>\n<td style=\"width: 20%;text-align: center\">558<\/td>\n<td style=\"width: 19.7356%;text-align: center\">627<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22024<\/td>\n<td style=\"width: 20%;text-align: center\">538<\/td>\n<td style=\"width: 20%;text-align: center\">566<\/td>\n<td style=\"width: 19.7356%;text-align: center\">638<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22564<\/td>\n<td style=\"width: 20%;text-align: center\">549<\/td>\n<td style=\"width: 20%;text-align: center\">574<\/td>\n<td style=\"width: 19.7356%;text-align: center\">649<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23234<\/td>\n<td style=\"width: 20%;text-align: center\">562<\/td>\n<td style=\"width: 20%;text-align: center\">584<\/td>\n<td style=\"width: 19.7356%;text-align: center\">662<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24184<\/td>\n<td style=\"width: 20%;text-align: center\">582<\/td>\n<td style=\"width: 20%;text-align: center\">598<\/td>\n<td style=\"width: 19.7356%;text-align: center\">682<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-8\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21729<\/td>\n<td style=\"width: 20%;text-align: center\">531<\/td>\n<td style=\"width: 20%;text-align: center\">559<\/td>\n<td style=\"width: 19.7356%;text-align: center\">631<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22269<\/td>\n<td style=\"width: 20%;text-align: center\">542<\/td>\n<td style=\"width: 20%;text-align: center\">567<\/td>\n<td style=\"width: 19.7356%;text-align: center\">642<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">22809<\/td>\n<td style=\"width: 20%;text-align: center\">553<\/td>\n<td style=\"width: 20%;text-align: center\">575<\/td>\n<td style=\"width: 19.7356%;text-align: center\">653<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23479<\/td>\n<td style=\"width: 20%;text-align: center\">566<\/td>\n<td style=\"width: 20%;text-align: center\">585<\/td>\n<td style=\"width: 19.7356%;text-align: center\">666<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24429<\/td>\n<td style=\"width: 20%;text-align: center\">586<\/td>\n<td style=\"width: 20%;text-align: center\">599<\/td>\n<td style=\"width: 19.7356%;text-align: center\">686<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-2-9\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"width: 99.7356%;border-color: lightgray\" border=\"1\">\n<thead>\n<tr>\n<th style=\"width: 20%\" width=\"20%\">\u00a0<\/th>\n<th style=\"width: 20%\" width=\"20%\">HP<\/th>\n<th style=\"width: 20%\" width=\"20%\">ATK<\/th>\n<th style=\"width: 20%\" width=\"20%\">DEF<\/th>\n<th style=\"width: 19.7356%\">SPD<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<th style=\"width: 20%\">Limit 0<\/th>\n<td style=\"width: 20%;text-align: center\">21994<\/td>\n<td style=\"width: 20%;text-align: center\">535<\/td>\n<td style=\"width: 20%;text-align: center\">561<\/td>\n<td style=\"width: 19.7356%;text-align: center\">635<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 1<\/th>\n<td style=\"width: 20%;text-align: center\">22534<\/td>\n<td style=\"width: 20%;text-align: center\">546<\/td>\n<td style=\"width: 20%;text-align: center\">569<\/td>\n<td style=\"width: 19.7356%;text-align: center\">646<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 2<\/th>\n<td style=\"width: 20%;text-align: center\">23074<\/td>\n<td style=\"width: 20%;text-align: center\">557<\/td>\n<td style=\"width: 20%;text-align: center\">577<\/td>\n<td style=\"width: 19.7356%;text-align: center\">657<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 3<\/th>\n<td style=\"width: 20%;text-align: center\">23744<\/td>\n<td style=\"width: 20%;text-align: center\">570<\/td>\n<td style=\"width: 20%;text-align: center\">587<\/td>\n<td style=\"width: 19.7356%;text-align: center\">670<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Limit 4<\/th>\n<td style=\"width: 20%;text-align: center\">24694<\/td>\n<td style=\"width: 20%;text-align: center\">590<\/td>\n<td style=\"width: 20%;text-align: center\">601<\/td>\n<td style=\"width: 19.7356%;text-align: center\">690<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 20%\">Special Effect<\/th>\n<td style=\"width: 20%;text-align: center\" colspan=\"4\">+40% Increased Critical Hit Chance<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<h2 class=\"sexypurple\" style=\"text-align: center\">Normal Attack<\/h2>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 1: Flash (\u9023\u9583)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">45 (58)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle\">\u00a0<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">None<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 2: Double Flash (\u30cb\u9023\u9583)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">70 (91)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle\">3<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">None<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Step 3: Murderous Flash (\u6ec5\u9023\u9583)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">95 (123)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle\">5<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th>Effect<\/th>\n<td colspan=\"3\">Reduce Resistance to<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Fatal Wound\" data-contentwrapper=\"osc_popover_1\"> Fatal Wound <\/button><div id=\"osc_popover_1\" style=\"display:none;\">Unit dies <br \/>\nIf Character is resistant to [Fatal Wound], it deals more damage instead<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    by 50% (3 turns)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 class=\"sexyblue\" style=\"text-align: center\">\nSkills<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-3\"><li class=\"active\"><a class=\"\" href=\"#pane-3-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-3-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-3-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-3-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Execution (\u8a85\u6bba)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">114 (150)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">Self<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle\">4<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle\">Effect<\/th>\n<td style=\"vertical-align: middle\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Put yourself in a state of<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Execution\" data-contentwrapper=\"osc_popover_2\"> Execution <\/button><div id=\"osc_popover_2\" style=\"display:none;\">At the end of the turn, attack the Enemy with the lowest HP<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    with a power of 114 (150) (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Sneaking Scar (\u30b9\u30cb\u30fc\u30ad\u30f3\u30b0\u30b9\u30ab\u30fc)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">116 (150)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">2 Different Random Targets<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle\">5<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle\">Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>Reduce Resistance to<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Fatal Wound\" data-contentwrapper=\"osc_popover_3\"> Fatal Wound <\/button><div id=\"osc_popover_3\" style=\"display:none;\">Unit dies <br \/>\nIf Character is resistant to [Fatal Wound], it deals more damage instead<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    by 50% (3 turns)<\/li>\n<\/ol>\n<p>Cool-down: 6 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-3-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%\" colspan=\"4\">Execution [Critical Hit Type] (\u8a85\u6bba\uff3b\u7834\uff3d)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">108 (140)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">Self<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle;width: 25%\">3<\/td>\n<th style=\"width: 25%\">Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle;width: 25%\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;width: 25%\">Effect<\/th>\n<td style=\"vertical-align: middle;width: 75%\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Put yourself in a state of<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Execution\" data-contentwrapper=\"osc_popover_4\"> Execution <\/button><div id=\"osc_popover_4\" style=\"display:none;\">At the end of the turn, attack the Enemy with the lowest HP<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    with a power of 108 (140) (2 turns)<\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Scissor Cyclone (\u30b7\u30b6\u30fc\u30b5\u30a4\u30af\u30ed\u30f3)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">154 (200)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">2 Random Targets<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle\">7<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle\">Effect<\/th>\n<td colspan=\"3\">\n<ol>\n<li>20% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Fatal Wound\" data-contentwrapper=\"osc_popover_5\"> Fatal Wound <\/button><div id=\"osc_popover_5\" style=\"display:none;\">Unit dies <br \/>\nIf Character is resistant to [Fatal Wound], it deals more damage instead<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>Increase evasion by 50%<\/li>\n<\/ol>\n<p>Cool-down: 6 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-3-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%\" colspan=\"4\">Execution [Critical Hit Type] (\u8a85\u6bba\uff3b\u6280\uff3d)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">93 (120)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">Self<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle;width: 25%\">3<\/td>\n<th style=\"width: 25%\">Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle;width: 25%\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;width: 25%\">Effect<\/th>\n<td style=\"vertical-align: middle;width: 75%\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>Put yourself in a state of<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Execution\" data-contentwrapper=\"osc_popover_6\"> Execution <\/button><div id=\"osc_popover_6\" style=\"display:none;\">At the end of the turn, attack the Enemy with the lowest HP<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    with a power of 93 (120) (2 turns)<\/li>\n<li>5% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Fatal Wound\" data-contentwrapper=\"osc_popover_7\"> Fatal Wound <\/button><div id=\"osc_popover_7\" style=\"display:none;\">Unit dies <br \/>\nIf Character is resistant to [Fatal Wound], it deals more damage instead<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<\/ol>\n<p>Cool-down: 5 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%\" colspan=\"4\">Sneaking Scar [Critical Hit Type] (\u30b9\u30cb\u30fc\u30ad\u30f3\u30b0\u30b9\u30ab\u30fc\uff3b\u6280\uff3d)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">108 (140)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">2 Different Random Targets<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle;width: 25%\">4<\/td>\n<th style=\"width: 25%\">Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle;width: 25%\">&#8211;<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;width: 25%\">Effect<\/th>\n<td style=\"width: 75%\" colspan=\"3\">\n<ol>\n<li>Reduce Resistance to<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Fatal Wound\" data-contentwrapper=\"osc_popover_8\"> Fatal Wound <\/button><div id=\"osc_popover_8\" style=\"display:none;\">Unit dies <br \/>\nIf Character is resistant to [Fatal Wound], it deals more damage instead<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    by 50% (3 turns)<\/li>\n<\/ol>\n<p>Cool-down: 6 turns<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n<h2 class=\"sexyred\" style=\"text-align: center\">\nElemental Blast<\/h2>\n<div class=\"\"><ul class=\"nav nav-tabs\" id=\"oscitas-tabs-4\"><li class=\"active\"><a class=\"\" href=\"#pane-4-0\" data-toggle=\"tab\">Default<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-4-1\" data-toggle=\"tab\">Law<\/a><\/li><li class=\"\"><a class=\"\" href=\"#pane-4-2\" data-toggle=\"tab\">Chaos<\/a><\/li><\/ul><div class=\"tab-content\"><div class=\"tab-pane active\" id=\"pane-4-0\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Graffiti Killer (\u30b0\u30e9\u30d5\u30a3\u30c6\u30a3\u30ad\u30e9\u30fc)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">214 (300)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle\">7<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle\">7<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle\">Effect<\/th>\n<td colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>10% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Fatal Wound\" data-contentwrapper=\"osc_popover_9\"> Fatal Wound <\/button><div id=\"osc_popover_9\" style=\"display:none;\">Unit dies <br \/>\nIf Character is resistant to [Fatal Wound], it deals more damage instead<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-4-1\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th colspan=\"4\">Assassin&#8217;s Daggers, Moonlit Night (\u5147\u5203\u30fb\u6727\u6708\u591c)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">485 (680)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">Single Target<\/td>\n<\/tr>\n<tr>\n<th>Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle\">10<\/td>\n<th>Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle\">10<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle\">Effect<\/th>\n<td colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>This attack always lands a Critical Hit<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><div class=\"tab-pane \" id=\"pane-4-2\"><\/p>\n<table  class=\"shrinkwrap12 pso2 table table-hover table table-hover\"  style=\"border-color: lightgray;width: 100%\" border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<th style=\"width: 100%\" colspan=\"4\">Graffiti Killer [Critical Hit Type] (\u30b0\u30e9\u30d5\u30a3\u30c6\u30a3\u30ad\u30e9\u30fc\uff3b\u6280\uff3d)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Power<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">210 (294)<\/td>\n<th style=\"width: 25%\">Target<\/th>\n<td style=\"width: 25%;text-align: center;vertical-align: middle\">All Enemies<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%\">Element Value Req.<\/th>\n<td style=\"text-align: center;vertical-align: middle;width: 25%\">7<\/td>\n<th style=\"width: 25%\">Element Value Cost<\/th>\n<td style=\"text-align: center;vertical-align: middle;width: 25%\">7<\/td>\n<\/tr>\n<tr>\n<th style=\"vertical-align: middle;width: 25%\">Effect<\/th>\n<td style=\"width: 75%\" colspan=\"3\">\n<p>[Fastest]<\/p>\n<ol>\n<li>10% chance to inflict<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Fatal Wound\" data-contentwrapper=\"osc_popover_10\"> Fatal Wound <\/button><div id=\"osc_popover_10\" style=\"display:none;\">Unit dies <br \/>\nIf Character is resistant to [Fatal Wound], it deals more damage instead<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    <\/li>\n<li>Reduce Resistance to<button class=\"osc_popover_new btn btn-xs btn-link \" data-placement=\"top\" data-toggle=\"popover\" data-trigger=\"click hover\" data-container=\"body\" type=\"button\" data-title=\"Fatal Wound\" data-contentwrapper=\"osc_popover_11\"> Fatal Wound <\/button><div id=\"osc_popover_11\" style=\"display:none;\">Unit dies <br \/>\nIf Character is resistant to [Fatal Wound], it deals more damage instead<\/div>\n    <script>\n       jQuery(document).ready(function(){\n        jQuery('.osc_popover_new').popover({\n            html:true,\n            content:function(){\n                return jQuery('#'+jQuery(this).data('contentwrapper')).html();\n            }\n\n        });\n        });\n    <\/script>\n    by 50% (3 turns)<\/li>\n<\/ol>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&lt; Back to Characters &nbsp; Luke (Law) Weak Hit Type Luke Attack Type Luke (Chaos) Critical Hit Type Rarity Faction Chaos Class Assassin Element Water Idola Lupus Fates Law Chaos Date 2020\/06\/01 Race Human Character Stats Default Law Chaos Normal Attack Step 1: Flash (\u9023\u9583) Power 45 (58) Target Single Target Element Value Req. \u00a0 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":567,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-6051","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PatEj8-1zB","_links":{"self":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/6051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/comments?post=6051"}],"version-history":[{"count":0,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/6051\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/pages\/567"}],"wp:attachment":[{"href":"https:\/\/bumped.org\/idola\/wp-json\/wp\/v2\/media?parent=6051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}